{"id":96444,"date":"2026-03-20T00:15:07","date_gmt":"2026-03-19T21:15:07","guid":{"rendered":"https:\/\/poland-consult.com\/?p=96444"},"modified":"2024-10-20T13:34:25","modified_gmt":"2024-10-20T10:34:25","slug":"zwolnienie-lekarskie-uop","status":"publish","type":"post","link":"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html","title":{"rendered":"\u042f\u043a \u0432\u0437\u044f\u0442\u0438 \u0442\u0430 \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u0438\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043f\u043e \u0423\u043c\u043e\u0432\u0456 \u043e \u043f\u0440\u0430\u0446\u0435?"},"content":{"rendered":"<p>\u042f\u043a\u0449\u043e \u043e\u0431\u0441\u0442\u0430\u0432\u0438\u043d\u0438 \u0441\u043a\u043b\u0430\u043b\u0438\u0441\u044f \u0442\u0430\u043a, \u0449\u043e \u043b\u044e\u0434\u0438\u043d\u0430 \u0437\u0430\u0445\u0432\u043e\u0440\u0456\u043b\u0430 \u0456 \u043d\u0435 \u043c\u043e\u0436\u0435 \u044f\u043a\u0438\u0439\u0441\u044c \u0447\u0430\u0441 \u043f\u0440\u0430\u0446\u044e\u0432\u0430\u0442\u0438, \u043b\u0456\u043a\u0430\u0440 \u0432\u0438\u043f\u0438\u0441\u0443\u0454 \u0457\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442. \u0417\u0430\u0433\u0430\u043b\u043e\u043c \u0446\u0435 \u0437\u043d\u0430\u0439\u043e\u043c\u0430 \u0431\u0430\u0433\u0430\u0442\u044c\u043e\u043c \u0443\u043a\u0440\u0430\u0457\u043d\u0446\u044f\u043c \u043f\u0440\u043e\u0446\u0435\u0434\u0443\u0440\u0430, \u043f\u043e\u0434\u0456\u0431\u043d\u0430 \u0434\u043e \u0431\u0456\u043b\u044c\u0448\u043e\u0441\u0442\u0456 \u043a\u0440\u0430\u0457\u043d \u0441\u0432\u0456\u0442\u0443.<\/p>\n<p>\u041e\u0434\u043d\u0430\u043a \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u0454 \u0441\u0432\u043e\u0457 \u0444\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0456 \u0434\u043b\u044f \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u0446\u044c\u043e\u0433\u043e \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u0430, \u0431\u0435\u0437 \u044f\u043a\u0438\u0445 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043d\u0435 \u0442\u0456\u043b\u044c\u043a\u0438 \u043d\u0435 \u0431\u0443\u0434\u0435 \u0441\u043f\u043b\u0430\u0447\u0435\u043d\u0438\u0439, \u0430 \u0439 \u0440\u043e\u0431\u0456\u0442\u043d\u0438\u043a\u0443 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0437\u0430\u0444\u0456\u043a\u0441\u043e\u0432\u0430\u043d\u043e\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/robota\/absencja-pracownicza.html\">\u043f\u0440\u043e\u0433\u0443\u043b<\/a>, \u043d\u0430\u0441\u043b\u0456\u0434\u043a\u043e\u043c \u044f\u043a\u043e\u0433\u043e \u043c\u043e\u0436\u0435 \u0441\u0442\u0430\u0442\u0438 \u0434\u043e\u0433\u0430\u043d\u0430 \u0447\u0438 \u043d\u0430\u0432\u0456\u0442\u044c \u0434\u0438\u0441\u0446\u0438\u043f\u043b\u0456\u043d\u0430\u0440\u043d\u0435 \u0437\u0432\u0456\u043b\u044c\u043d\u0435\u043d\u043d\u044f.<\/p>\n<p>\u042f\u043a \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e \u043e\u0444\u043e\u0440\u043c\u0438\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456, \u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u0443 \u0446\u044c\u043e\u043c\u0443 \u043c\u0430\u0442\u0435\u0440\u0456\u0430\u043b\u0456 \u00ab\u041f\u043e\u043b\u044c\u0441\u044c\u043a\u043e\u0433\u043e \u043a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442\u0430\u00bb.<\/p>\n<p><!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-transparent ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A9%D0%BE-%D1%82%D0%B0%D0%BA%D0%B5-L4-ZUS-ZLA-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\" >\u0429\u043e \u0442\u0430\u043a\u0435 L4 (ZUS ZLA) \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%AF%D0%BA-%D0%B2%D0%B8%D0%B3%D0%BB%D1%8F%D0%B4%D0%B0%D1%94-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D0%BB%D0%B8%D1%81%D1%82-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\" >\u042f\u043a \u0432\u0438\u0433\u043b\u044f\u0434\u0430\u0454 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A2%D0%B8%D0%BF%D0%B8-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D1%85-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96-%D1%82%D0%B0-%D0%BA%D0%BE%D0%B4%D0%B8-%D0%B7%D0%B0%D1%85%D0%B2%D0%BE%D1%80%D1%8E%D0%B2%D0%B0%D0%BD%D1%8C\" >\u0422\u0438\u043f\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0445 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u0442\u0430 \u043a\u043e\u0434\u0438 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u044c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A5%D1%82%D0%BE-%D0%BD%D0%B5-%D0%BC%D0%BE%D0%B6%D0%B5-%D0%BE%D1%82%D1%80%D0%B8%D0%BC%D0%B0%D1%82%D0%B8-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D0%B2%D0%B0%D0%BD%D0%B8%D0%B9-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9\" >\u0425\u0442\u043e (\u043d\u0435) \u043c\u043e\u0436\u0435 \u043e\u0442\u0440\u0438\u043c\u0430\u0442\u0438 \u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9A%D0%BE%D0%BB%D0%B8-%D0%BF%D0%BE%D1%87%D0%B8%D0%BD%D0%B0%D1%94-%D0%B4%D1%96%D1%8F%D1%82%D0%B8-%D1%81%D1%82%D1%80%D0%B0%D1%85%D0%BE%D0%B2%D0%BA%D0%B0-%D0%B7-%D1%8F%D0%BA%D0%BE%D0%B3%D0%BE-%D0%B4%D0%BD%D1%8F-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D1%8E%D1%82%D1%8C-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9\" >\u041a\u043e\u043b\u0438 \u043f\u043e\u0447\u0438\u043d\u0430\u0454 \u0434\u0456\u044f\u0442\u0438 \u0441\u0442\u0440\u0430\u0445\u043e\u0432\u043a\u0430: \u0437 \u044f\u043a\u043e\u0433\u043e \u0434\u043d\u044f \u043e\u043f\u043b\u0430\u0447\u0443\u044e\u0442\u044c \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%AF%D0%BA-%D0%B2%D0%B7%D1%8F%D1%82%D0%B8-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\" >\u042f\u043a \u0432\u0437\u044f\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9E%D1%82%D1%80%D0%B8%D0%BC%D0%B0%D0%BD%D0%BD%D1%8F-e-ZLA\" >\u041e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f e-ZLA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9F%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%BB%D0%B5%D0%BD%D0%BD%D1%8F-%D1%80%D0%BE%D0%B1%D0%BE%D1%82%D0%BE%D0%B4%D0%B0%D0%B2%D1%86%D1%8F-%D0%BF%D1%80%D0%BE-%D1%85%D0%B2%D0%BE%D1%80%D0%BE%D0%B1%D1%83\" >\u041f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u043f\u0440\u043e \u0445\u0432\u043e\u0440\u043e\u0431\u0443<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A5%D1%82%D0%BE-%D1%96-%D1%8F%D0%BA-%D0%BC%D0%BE%D0%B6%D0%B5-%D0%BF%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%B8%D1%82%D0%B8\" >\u0425\u0442\u043e \u0456 \u044f\u043a \u043c\u043e\u0436\u0435 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9D%D0%B0%D1%81%D0%BB%D1%96%D0%B4%D0%BA%D0%B8-%D0%B2%D1%96%D0%B4%D1%81%D1%83%D1%82%D0%BD%D0%BE%D1%81%D1%82%D1%96-%D0%BF%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%BB%D0%B5%D0%BD%D0%BD%D1%8F\" >\u041d\u0430\u0441\u043b\u0456\u0434\u043a\u0438 \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u043e\u0441\u0442\u0456 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9A%D0%BE%D0%BB%D0%B8-%D0%BF%D0%BE%D1%87%D0%B8%D0%BD%D0%B0%D1%94-%D0%B4%D1%96%D1%8F%D1%82%D0%B8-ZUS-ZLA\" >\u041a\u043e\u043b\u0438 \u043f\u043e\u0447\u0438\u043d\u0430\u0454 \u0434\u0456\u044f\u0442\u0438 ZUS ZLA?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%AF%D0%BA-%D0%BF%D0%B5%D1%80%D0%B5%D0%B2%D1%96%D1%80%D0%B8%D1%82%D0%B8-%D1%81%D0%B2%D1%96%D0%B9-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\" >\u042f\u043a \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u0438\u0442\u0438 \u0441\u0432\u0456\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%AF%D0%BA-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D1%94%D1%82%D1%8C%D1%81%D1%8F-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96-%D0%BF%D0%BE-UoP\" >\u042f\u043a \u043e\u043f\u043b\u0430\u0447\u0443\u0454\u0442\u044c\u0441\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043f\u043e UoP?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%AF%D0%BA-%D0%B2%D0%B8%D0%B7%D0%BD%D0%B0%D1%87%D0%B0%D1%94%D1%82%D1%8C%D1%81%D1%8F-%D1%80%D0%BE%D0%B7%D1%80%D0%B0%D1%85%D1%83%D0%BD%D0%BA%D0%BE%D0%B2%D0%B0-%D0%B1%D0%B0%D0%B7%D0%B0-%D0%BD%D0%B0-%D0%BE%D0%BF%D0%BB%D0%B0%D1%82%D1%83-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%BE%D0%B3%D0%BE\" >\u042f\u043a \u0432\u0438\u0437\u043d\u0430\u0447\u0430\u0454\u0442\u044c\u0441\u044f \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u043e\u0432\u0430 \u0431\u0430\u0437\u0430 \u043d\u0430 \u043e\u043f\u043b\u0430\u0442\u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A7%D0%B8-%D0%BC%D0%BE%D0%B6%D0%BD%D0%B0-%D0%B4%D0%BE%D0%BC%D0%BE%D0%B2%D0%B8%D1%82%D0%B8%D1%81%D1%8F-%D0%B7-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%B5%D0%BC-%D1%8F%D0%BA%D1%89%D0%BE-%D0%BD%D0%B5-%D1%85%D0%B2%D0%BE%D1%80%D1%96%D1%94%D1%88\" >\u0427\u0438 \u043c\u043e\u0436\u043d\u0430 \u0434\u043e\u043c\u043e\u0432\u0438\u0442\u0438\u0441\u044f \u0437 \u043b\u0456\u043a\u0430\u0440\u0435\u043c, \u044f\u043a\u0449\u043e \u043d\u0435 \u0445\u0432\u043e\u0440\u0456\u0454\u0448?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%A7%D0%B8-%D0%BC%D0%BE%D0%B6%D0%B5-ZUS-%D0%B2%D1%96%D0%B4%D0%BA%D0%BB%D0%B8%D0%BA%D0%B0%D1%82%D0%B8-%D1%81%D0%BF%D0%BB%D0%B0%D1%82%D1%83-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%BE%D0%B3%D0%BE-%D0%B7%D0%B0-%D0%BF%D0%BE%D1%80%D1%83%D1%88%D0%B5%D0%BD%D0%BD%D1%8F\" >\u0427\u0438 \u043c\u043e\u0436\u0435 ZUS \u0432\u0456\u0434\u043a\u043b\u0438\u043a\u0430\u0442\u0438 \u0441\u043f\u043b\u0430\u0442\u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u0437\u0430 \u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"#\" data-href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/zwolnienie-lekarskie-uop.html\/#%D0%9F%D0%BE%D1%88%D0%B8%D1%80%D0%B5%D0%BD%D1%96-%D0%B7%D0%B0%D0%BF%D0%B8%D1%82%D0%B0%D0%BD%D0%BD%D1%8F\" >\u041f\u043e\u0448\u0438\u0440\u0435\u043d\u0456 \u0437\u0430\u043f\u0438\u0442\u0430\u043d\u043d\u044f<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A9%D0%BE-%D1%82%D0%B0%D0%BA%D0%B5-L4-ZUS-ZLA-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\"><\/span>\u0429\u043e \u0442\u0430\u043a\u0435 L4 (ZUS ZLA) \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"colored\">Zwolnienie L4 (\u0437\u0432\u0456\u043b\u044c\u043d\u0435\u043d\u043d\u044f \u0432\u0456\u0434 \u0440\u043e\u0431\u043e\u0442\u0438 L4) \u2013 \u0446\u0435 \u0434\u0443\u0436\u0435 \u043f\u043e\u0448\u0438\u0440\u0435\u043d\u0438\u0439 \u043c\u043e\u0432\u043d\u0438\u0439 \u043e\u0431\u043e\u0440\u043e\u0442, \u0449\u043e \u043e\u0437\u043d\u0430\u0447\u0430\u0454 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456. \u0420\u0430\u043d\u0456\u0448\u0435 \u0441\u0430\u043c\u0435 \u0446\u0435\u0439 \u0442\u0435\u0440\u043c\u0456\u043d \u0431\u0443\u0432 \u043e\u0444\u0456\u0446\u0456\u0439\u043d\u0438\u043c, \u043f\u0440\u043e\u0442\u0435 \u043d\u0438\u043d\u0456 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u044e\u0442\u044c\u0441\u044f \u0456\u043d\u0448\u0456 \u0442\u0435\u0440\u043c\u0456\u043d\u0438 \u2013 ZUS ZLA, \u044f\u043a \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u044f\u043a \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442 \u0432\u0437\u0430\u0433\u0430\u043b\u0456, \u0447\u0438 e-ZLA, \u044f\u043a \u0439\u043e\u0433\u043e \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0430 \u0432\u0435\u0440\u0441\u0456\u044f.<\/div>\n<p>\u0412\u043e\u0434\u043d\u043e\u0447\u0430\u0441 \u0441\u0430\u043c\u0435 \u043d\u0430\u0439\u043c\u0435\u043d\u0443\u0432\u0430\u043d\u043d\u044f L4 \u043d\u0430\u0441\u0442\u0456\u043b\u044c\u043a\u0438 \u0449\u0456\u043b\u044c\u043d\u043e \u0437\u0430\u0444\u0456\u043a\u0441\u0443\u0432\u0430\u043b\u043e\u0441\u044f \u0443 \u043c\u043e\u0432\u043d\u0456\u0439 \u0442\u0440\u0430\u0434\u0438\u0446\u0456\u0457 \u043f\u043e\u043b\u044f\u043a\u0456\u0432, \u0449\u043e \u0443 \u0440\u043e\u0437\u043c\u043e\u0432\u043d\u0456\u0439 \u043c\u043e\u0432\u0456 \u0456 \u043b\u0456\u043a\u0430\u0440\u0456\u0432, \u0456 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0456\u0432, \u0456 \u0447\u0438\u043d\u043e\u0432\u043d\u0438\u043a\u0456\u0432 \u0439\u043e\u0433\u043e \u043c\u043e\u0436\u043d\u0430 \u0437\u0443\u0441\u0442\u0440\u0456\u0442\u0438 \u043f\u043e\u0432\u0441\u044e\u0434\u043d\u043e.<\/p>\n<p>\u0429\u043e \u0441\u0442\u043e\u0441\u0443\u0454\u0442\u044c\u0441\u044f e-ZLA, \u0442\u043e \u0441\u0430\u043c\u0435 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0438\u0439 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442 \u043d\u0430\u0434\u0430\u0454\u0442\u044c\u0441\u044f \u0437\u0430\u0440\u0430\u0437 \u0443 \u043f\u0435\u0440\u0435\u0432\u0430\u0436\u043d\u0456\u0439 \u0431\u0456\u043b\u044c\u0448\u043e\u0441\u0442\u0456 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 (\u0434\u0435\u044f\u043a\u0456 \u0432\u0438\u043d\u044f\u0442\u043a\u0438 \u0440\u043e\u0437\u0433\u043b\u044f\u043d\u0435\u043c\u043e \u0434\u0430\u043b\u0456).<\/p>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\">\u0427\u0438\u0442\u0430\u044e\u0447\u0438 \u0446\u044e \u0441\u0442\u0430\u0442\u0442\u044e, \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e \u0440\u043e\u0437\u0443\u043c\u0456\u0442\u0438, \u0449\u043e \u043f\u043e\u043d\u044f\u0442\u0442\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442, L4 \u0442\u0430 ZUS ZLA \u0443 \u0434\u0430\u043d\u043e\u043c\u0443 \u043c\u0430\u0442\u0435\u0440\u0456\u0430\u043b\u0456 \u0441\u0438\u043d\u043e\u043d\u0456\u043c\u0438, \u0430 e-ZLA \u2013 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0438\u0439 \u0444\u043e\u0440\u043c\u0430\u0442 \u0442\u043e\u0433\u043e \u0441\u0430\u043c\u043e\u0433\u043e \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u0430.<\/div><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%D0%AF%D0%BA-%D0%B2%D0%B8%D0%B3%D0%BB%D1%8F%D0%B4%D0%B0%D1%94-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D0%BB%D0%B8%D1%81%D1%82-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\"><\/span>\u042f\u043a \u0432\u0438\u0433\u043b\u044f\u0434\u0430\u0454 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0429\u0435 \u0440\u0430\u0437 \u2013 \u0443 \u043f\u0435\u0440\u0435\u0432\u0430\u0436\u043d\u0456\u0439 \u0431\u0456\u043b\u044c\u0448\u043e\u0441\u0442\u0456 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u0432 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u043e\u043c\u0443 \u0432\u0438\u0433\u043b\u044f\u0434\u0456. \u0426\u0435 \u043e\u0437\u043d\u0430\u0447\u0430\u0454, \u0449\u043e \u0434\u043e\u0441\u0442\u0443\u043f \u0434\u043e \u043d\u044c\u043e\u0433\u043e \u0437\u0430\u0456\u043d\u0442\u0435\u0440\u0435\u0441\u043e\u0432\u0430\u043d\u0456 \u043e\u0441\u043e\u0431\u0438 \u043e\u0442\u0440\u0438\u043c\u0443\u044e\u0442\u044c \u0447\u0435\u0440\u0435\u0437 \u0456\u043d\u0442\u0435\u0440\u0444\u0435\u0439\u0441 \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u043e\u0433\u043e\u00a0\u041f\u0417. \u041d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u0447\u0435\u0440\u0435\u0437\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/europa\/polska\/dovidnik\/pue-zus.html\">PUE ZUS<\/a>\u00a0\u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442 \u043c\u043e\u0436\u0435 \u0432\u0438\u0433\u043b\u044f\u0434\u0430\u0442\u0438 \u0442\u0430\u043a:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/poland-consult.com\/wp-content\/uploads\/2024\/01\/bolnichnyj-list-111.jpg\" alt=\"\" width=\"700\" height=\"684\" class=\"alignnone size-full wp-image-96349\"><\/p>\n<p>\u0420\u0430\u0437\u043e\u043c \u0437 \u0442\u0438\u043c, \u0443 \u0432\u0438\u043d\u044f\u0442\u043a\u043e\u0432\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445, \u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u043f\u0440\u0438 \u0442\u0440\u0438\u0432\u0430\u043b\u0456\u0439 \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u043e\u0441\u0442\u0456 \u0456\u043d\u0442\u0435\u0440\u043d\u0435\u0442\u0443 \u0430\u0431\u043e \u043d\u0430 \u0432\u0438\u043c\u043e\u0433\u0443 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430, e-ZLA \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0440\u043e\u0437\u0434\u0440\u0443\u043a\u043e\u0432\u0430\u043d\u0438\u0439 (\ud83d\udcc4 <a href=\"https:\/\/poland-consult.com\/wp-content\/uploads\/2024\/02\/e-ZLA-ZUS.pdf\" target=\"_blank\" rel=\"noopener\">\u0431\u043b\u0430\u043d\u043a<\/a>).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A2%D0%B8%D0%BF%D0%B8-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D1%85-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96-%D1%82%D0%B0-%D0%BA%D0%BE%D0%B4%D0%B8-%D0%B7%D0%B0%D1%85%D0%B2%D0%BE%D1%80%D1%8E%D0%B2%D0%B0%D0%BD%D1%8C\"><\/span>\u0422\u0438\u043f\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0445 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u0442\u0430 \u043a\u043e\u0434\u0438 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u044c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0414\u0456\u0430\u0433\u043d\u043e\u0437, \u044f\u043a\u0438\u0439 \u043b\u0456\u043a\u0430\u0440 \u0441\u0442\u0430\u0432\u0438\u0442\u044c \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u043e\u0432\u0456, \u0432\u0456\u0434\u043d\u043e\u0441\u0438\u0442\u044c\u0441\u044f \u0432 \u041f\u043e\u043b\u044c\u0449\u0456 \u0434\u043e \u043f\u0435\u0440\u0441\u043e\u043d\u0430\u043b\u044c\u043d\u0438\u0445 \u0434\u0430\u043d\u0438\u0445 \u0456 \u043d\u0435 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0440\u043e\u0437\u0433\u043e\u043b\u043e\u0448\u0435\u043d\u0438\u0439 \u0442\u0440\u0435\u0442\u0456\u043c \u043e\u0441\u043e\u0431\u0430\u043c, \u0443 \u0442\u043e\u043c\u0443 \u0447\u0438\u0441\u043b\u0456 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044e.<\/p>\n<p>\u041e\u0434\u043d\u0430\u043a L4 \u043c\u0456\u0441\u0442\u0438\u0442\u044c \u043a\u043e\u0434\u0438, \u0449\u043e \u043a\u043b\u0430\u0441\u0438\u0444\u0456\u043a\u0443\u044e\u0442\u044c \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0437\u0430 \u043e\u043a\u0440\u0435\u043c\u0438\u043c\u0438 \u0433\u0440\u0443\u043f\u0430\u043c\u0438:<\/p>\n<table>\n<thead>\n<tr>\n<th scope=\"col\">\u041b\u0456\u0442\u0435\u0440\u043d\u0438\u0439 \u043a\u043e\u0434<\/th>\n<th scope=\"col\">\u0422\u0438\u043f \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u043e\u0441\u0442\u0456<\/th>\n<th scope=\"col\">\u041d\u0430\u0441\u043b\u0456\u0434\u043a\u0438<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>A<\/td>\n<td>\u041f\u043e\u0432\u0442\u043e\u0440\u043d\u0435 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f \u043f\u043e \u0442\u043e\u043c\u0443 \u0436 \u0434\u0456\u0430\u0433\u043d\u043e\u0437\u0443 \u0447\u0435\u0440\u0435\u0437 \u043c\u0435\u043d\u0448\u0435 \u043d\u0456\u0436 60 \u0434\u0456\u0431 \u0437 \u043f\u043e\u043f\u0435\u0440\u0435\u0434\u043d\u044c\u043e\u0433\u043e \u0432\u0438\u043f\u0430\u0434\u043a\u0443<\/td>\n<td>\u0412\u043f\u043b\u0438\u0432\u0430\u0454 \u043d\u0430 \u0432\u0456\u0440\u043d\u0456\u0441\u0442\u044c \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u0438\u0445 \u043f\u0435\u0440\u0456\u043e\u0434\u0456\u0432<\/td>\n<\/tr>\n<tr>\n<td>B<\/td>\n<td><a href=\"https:\/\/poland-consult.com\/uk\/robota\/trudovi-prava-vagitnih.html\">\u0412\u0430\u0433\u0456\u0442\u043d\u0456\u0441\u0442\u044c<\/a><\/td>\n<td>\u041f\u0440\u0438\u0432\u043e\u0434\u0438\u0442\u044c \u0434\u043e 100% \u043e\u043f\u043b\u0430\u0442\u0438, \u0430 \u0442\u0430\u043a\u043e\u0436 \u0454 \u043e\u0444\u0456\u0446\u0456\u0439\u043d\u0438\u043c \u043e\u043f\u043e\u0432\u0456\u0449\u0435\u043d\u043d\u044f\u043c \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u043f\u0440\u043e \u0432\u0430\u0433\u0456\u0442\u043d\u0456\u0441\u0442\u044c \u0440\u043e\u0431\u0456\u0442\u043d\u0438\u0446\u0456.<\/td>\n<\/tr>\n<tr>\n<td>C<\/td>\n<td>\u0417\u043b\u043e\u0432\u0436\u0438\u0432\u0430\u043d\u043d\u044f \u0430\u043b\u043a\u043e\u0433\u043e\u043b\u0435\u043c<\/td>\n<td>\u041f\u0435\u0440\u0448\u0456 5 \u0434\u043d\u0456\u0432 \u0442\u0430\u043a\u043e\u0433\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043d\u0435 \u043e\u043f\u043b\u0430\u0447\u0443\u044e\u0442\u044c\u0441\u044f<\/td>\n<\/tr>\n<tr>\n<td>D<\/td>\n<td>\u0422\u0443\u0431\u0435\u0440\u043a\u0443\u043b\u044c\u043e\u0437<\/td>\n<td>\u0410\u043d\u0430\u043b\u043e\u0433\u0456\u0447\u043d\u043e \u043a\u043e\u0434\u0443 \u0410 \u0432\u043f\u043b\u0438\u0432\u0430\u0454 \u043d\u0430 \u0432\u0438\u043f\u043b\u0430\u0442\u0438, \u0430\u043b\u0435 \u043f\u043e\u0432&#8217;\u044f\u0437\u0430\u043d\u0456 \u0437 \u043a\u043e\u043d\u043a\u0440\u0435\u0442\u043d\u0438\u043c \u0434\u0456\u0430\u0433\u043d\u043e\u0437\u043e\u043c<\/td>\n<\/tr>\n<tr>\n<td>E<\/td>\n<td>\u0406\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0435 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f, \u0456\u043d\u043a\u0443\u0431\u0430\u0446\u0456\u0439\u043d\u0438\u0439 \u043f\u0435\u0440\u0456\u043e\u0434 \u044f\u043a\u043e\u0433\u043e \u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u044c \u043f\u043e\u043d\u0430\u0434 14 \u0434\u043d\u0456\u0432<\/td>\n<td>\u0423 \u0442\u043e\u043c\u0443 \u0447\u0438\u0441\u043b\u0456 \u0454 \u043f\u0456\u0434\u0441\u0442\u0430\u0432\u0430 \u0434\u043b\u044f \u043e\u043f\u043b\u0430\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043f\u0456\u0441\u043b\u044f \u0437\u0432\u0456\u043b\u044c\u043d\u0435\u043d\u043d\u044f<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\">\u041a\u0440\u0456\u043c \u0446\u044c\u043e\u0433\u043e, \u0441\u043b\u0456\u0434 \u043f\u0430\u043c&#8217;\u044f\u0442\u0430\u0442\u0438, \u0449\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u0432\u0438\u0434\u0430\u0454\u0442\u044c\u0441\u044f \u043d\u0430 \u0442\u0435\u0440\u043c\u0456\u043d \u043d\u0435 \u0431\u0456\u043b\u044c\u0448\u0435 182 \u0434\u043d\u0456\u0432 (\u0434\u043b\u044f \u0432\u0430\u0433\u0456\u0442\u043d\u0438\u0445 \u0442\u0430 \u043f\u0440\u0438 \u0442\u0443\u0431\u0435\u0440\u043a\u0443\u043b\u044c\u043e\u0437\u0456 \u2013 \u0434\u043e 270 \u0434\u043d\u0456\u0432). \u042f\u043a\u0449\u043e \u0445\u0432\u043e\u0440\u043e\u0431\u0443 \u043d\u0435 \u0432\u0434\u0430\u043b\u043e\u0441\u044f \u0432\u0438\u043b\u0456\u043a\u0443\u0432\u0430\u0442\u0438 \u0437\u0430 \u0446\u0435\u0439 \u043f\u0435\u0440\u0456\u043e\u0434, \u043f\u0430\u0446\u0456\u0454\u043d\u0442 \u043f\u043e\u0432\u0438\u043d\u0435\u043d \u0430\u0431\u043e\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/europa\/polska\/prava-invalidiv\/niepelnosprawnosc.html\">\u043e\u0444\u043e\u0440\u043c\u0438\u0442\u0438 \u0456\u043d\u0432\u0430\u043b\u0456\u0434\u043d\u0456\u0441\u0442\u044c <\/a>, \u0430\u0431\u043e \u0442.\u0437\u0432.\u00a0\u0440\u0435\u0430\u0431\u0456\u043b\u0456\u0442\u0430\u0446\u0456\u0439\u043d\u0443 \u043f\u0456\u043b\u044c\u0433\u0443. \u0423 \u0446\u0456\u0439 \u0441\u0442\u0430\u0442\u0442\u0456 \u0440\u043e\u0437\u0433\u043b\u044f\u0434\u0430\u044e\u0442\u044c\u0441\u044f \u043b\u0438\u0448\u0435 \u0432\u0438\u043f\u0430\u0434\u043a\u0438, \u0449\u043e \u0432\u0445\u043e\u0434\u044f\u0442\u044c \u0443 \u0437\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d \u043d\u0430\u0434\u0430\u043d\u043d\u044f L4.<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A5%D1%82%D0%BE-%D0%BD%D0%B5-%D0%BC%D0%BE%D0%B6%D0%B5-%D0%BE%D1%82%D1%80%D0%B8%D0%BC%D0%B0%D1%82%D0%B8-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D0%B2%D0%B0%D0%BD%D0%B8%D0%B9-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9\"><\/span>\u0425\u0442\u043e (\u043d\u0435) \u043c\u043e\u0436\u0435 \u043e\u0442\u0440\u0438\u043c\u0430\u0442\u0438 \u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u041e\u043f\u043b\u0430\u0442\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043b\u0438\u0441\u0442\u0430 \u043c\u043e\u0436\u043b\u0438\u0432\u0430 \u043b\u0438\u0448\u0435 \u043e\u0441\u043e\u0431\u0430\u043c, \u044f\u043a\u0456 \u0432\u0438\u043f\u043b\u0430\u0447\u0443\u044e\u0442\u044c \u0437\u0456 \u0441\u0432\u043e\u0457\u0445 \u0434\u043e\u0445\u043e\u0434\u0456\u0432\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/europa\/polska\/dovidnik\/zus.html\">\u0432\u043d\u0435\u0441\u043a\u0438 \u0434\u043e ZUS<\/a>, \u0456\u043c\u0435\u043d\u043e\u0432\u0430\u043d\u0456 ubezpieczenie chorobowe (sk\u0142adka chorobowe \u0430\u0431\u043e \u043f\u0440\u043e\u0441\u0442\u043e chorobowa).<\/p>\n<p>\u041d\u0430\u0433\u0430\u0434\u0430\u0454\u043c\u043e, \u0449\u043e \u043f\u043e\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/robota\/dogovory\/umowy-o-prace\/trudovyj.html\">\u0443\u043c\u043e\u0432\u0456 \u043e \u043f\u0440\u0430\u0446\u0435<\/a>\u00a0\u0446\u0435\u0439 \u043f\u043b\u0430\u0442\u0456\u0436 \u0454 \u043e\u0431\u043e\u0432&#8217;\u044f\u0437\u043a\u043e\u0432\u0438\u043c, \u0430 \u0437\u043d\u0430\u0447\u0438\u0442\u044c \u0443\u0441\u0456, \u0445\u0442\u043e \u043c\u0430\u0454 \u0434\u0430\u043d\u0438\u0439 \u0442\u0438\u043f \u0434\u043e\u0433\u043e\u0432\u043e\u0440\u0443 \u0437\u0430 \u0443\u043c\u043e\u0432\u0447\u0430\u043d\u043d\u044f\u043c, \u043c\u0430\u044e\u0442\u044c \u043f\u0440\u0430\u0432\u043e \u043d\u0430 \u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 (\u0437 \u0434\u043d\u044f \u043f\u043e\u0447\u0430\u0442\u043a\u0443 \u0434\u0456\u0457 \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f).<\/p>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\"><a href=\"https:\/\/poland-consult.com\/uk\/robota\/likarnyanij\/l4-po-umowa-zlecenia.html\">\u041e\u043f\u043b\u0430\u0442\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043f\u043e \u0443\u043c\u043e\u0432\u0456 \u0437\u043b\u0435\u0446\u0435\u043d\u044f<\/a>, \u0430 \u0442\u0430\u043a\u043e\u0436\u00a0\u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0434\u043b\u044f \u043f\u0456\u0434\u043f\u0440\u0438\u0454\u043c\u0446\u0456\u0432\u00a0\u0443 \u0446\u0456\u0439 \u0441\u0442\u0430\u0442\u0442\u0456 \u043d\u0435 \u0440\u043e\u0437\u0433\u043b\u044f\u0434\u0430\u044e\u0442\u044c\u0441\u044f, \u0430\u043b\u0435 \u0437\u0430 \u043d\u0430\u044f\u0432\u043d\u043e\u0441\u0442\u0456 \u0434\u043e\u0431\u0440\u043e\u0432\u0456\u043b\u044c\u043d\u043e\u0433\u043e \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0456\u044f \u043e\u0444\u043e\u0440\u043c\u043b\u0435\u043d\u043d\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u0431\u0430\u0433\u0430\u0442\u043e \u0432 \u0447\u043e\u043c\u0443 \u0441\u0445\u043e\u0436\u0430. \u0412\u0438\u043d\u044f\u0442\u043a\u043e\u043c \u0454 JDG (\u0424\u041e\u041f), \u044f\u043a\u0456 \u043f\u043e\u0432\u0438\u043d\u043d\u0456 \u0441\u0430\u043c\u043e\u0441\u0442\u0456\u0439\u043d\u043e \u0441\u043f\u043e\u0432\u0456\u0449\u0430\u0442\u0438 ZUS \u043f\u0440\u043e \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f.<\/div><\/div>\n<p>\u0412\u043e\u0434\u043d\u043e\u0447\u0430\u0441 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u00a0<strong>\u043d\u0435\u043c\u0430\u0454 \u043f\u0440\u0430\u0432\u0430 \u043d\u0430 \u043e\u043f\u043b\u0430\u0442\u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e <\/strong>, \u044f\u043a\u0449\u043e:<\/p>\n<ul>\n<li>\u041d\u0435 \u043f\u0440\u043e\u0439\u0448\u043e\u0432 30-\u0434\u0435\u043d\u043d\u0438\u0439 \u043f\u0435\u0440\u0456\u043e\u0434 \u043f\u0456\u0441\u043b\u044f \u0439\u043e\u0433\u043e \u043f\u0440\u0430\u0446\u0435\u0432\u043b\u0430\u0448\u0442\u0443\u0432\u0430\u043d\u043d\u044f (\u0434\u043e \u0446\u044c\u043e\u0433\u043e \u043f\u0438\u0442\u0430\u043d\u043d\u044f \u0449\u0435 \u043f\u043e\u0432\u0435\u0440\u043d\u0435\u043c\u043e\u0441\u044c \u0434\u0430\u043b\u0456).<\/li>\n<li>\u041d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c \u0441\u043f\u0440\u0438\u0447\u0438\u043d\u0435\u043d\u0430 \u0437\u043b\u043e\u0432\u0436\u0438\u0432\u0430\u043d\u043d\u044f\u043c \u0430\u043b\u043a\u043e\u0433\u043e\u043b\u0435\u043c\u00a0(\u0432\u0438\u043f\u043b\u0430\u0442\u0430 \u043d\u0435 \u043d\u0430\u0447\u0438\u0441\u043b\u044f\u0454\u0442\u044c\u0441\u044f \u0437\u0430 \u043f\u0435\u0440\u0448\u0456 5 \u0434\u043d\u0456\u0432 \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u043e\u0441\u0442\u0456).<\/li>\n<li>\u041d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c \u043d\u0430\u0441\u0442\u0430\u043b\u0430 \u0432\u043d\u0430\u0441\u043b\u0456\u0434\u043e\u043a \u0443\u043c\u0438\u0441\u043d\u043e\u0433\u043e \u0437\u043b\u043e\u0447\u0438\u043d\u0443 \u0430\u0431\u043e \u043f\u0440\u0430\u0432\u043e\u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f, \u0432\u0447\u0438\u043d\u0435\u043d\u043e\u0433\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u043e\u043c, \u0449\u043e \u043f\u0456\u0434\u0442\u0432\u0435\u0440\u0434\u0436\u0435\u043d\u043e \u0440\u0456\u0448\u0435\u043d\u043d\u044f\u043c \u0441\u0443\u0434\u0443, \u044f\u043a\u0435 \u043d\u0430\u0431\u0440\u0430\u043b\u043e \u0447\u0438\u043d\u043d\u043e\u0441\u0442\u0456.<\/li>\n<li>\u041d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c \u0441\u0442\u0430\u043b\u0430\u0441\u044f \u043f\u0456\u0434 \u0447\u0430\u0441 \u043d\u0435\u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u043e\u0457 \u0432\u0456\u0434\u043f\u0443\u0441\u0442\u043a\u0438,\u00a0\u0432\u0456\u0434\u043f\u0443\u0441\u0442\u043a\u0438 \u043f\u043e \u0434\u043e\u0433\u043b\u044f\u0434\u0443 \u0437\u0430 \u0434\u0438\u0442\u0438\u043d\u043e\u044e, \u0442\u0438\u043c\u0447\u0430\u0441\u043e\u0432\u043e\u0433\u043e \u0430\u0440\u0435\u0448\u0442\u0443 \u0430\u0431\u043e \u0443\u0432&#8217;\u044f\u0437\u043d\u0435\u043d\u043d\u044f.<\/li>\n<li>\u041f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0430 \u0443\u0441\u0443\u043d\u0443\u0442\u043e \u0432\u0456\u0434 \u0440\u043e\u0431\u043e\u0442\u0438 \u0437\u0430 \u043f\u0456\u0434\u043e\u0437\u0440\u043e\u044e \u0432 \u0442\u043e\u043c\u0443, \u0449\u043e \u0432\u0456\u043d \u043f\u0435\u0440\u0435\u043d\u043e\u0441\u043d\u0438\u043a \u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u043e\u0433\u043e \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f, \u044f\u043a\u0449\u043e \u0442\u0430\u043a\u0438\u0439 \u0440\u043e\u0431\u0456\u0442\u043d\u0438\u043a \u043d\u0435 \u043f\u0440\u0438\u0441\u0442\u0443\u043f\u0438\u0432 \u0434\u043e \u0456\u043d\u0448\u043e\u0457 \u0437\u0430\u043f\u0440\u043e\u043f\u043e\u043d\u043e\u0432\u0430\u043d\u043e\u0457 \u0440\u043e\u0431\u043e\u0442\u0438, \u043d\u0435 \u0437\u0430\u0431\u043e\u0440\u043e\u043d\u0435\u043d\u043e\u0457 \u0442\u0430\u043a\u0438\u043c \u043e\u0441\u043e\u0431\u0430\u043c, \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u043e\u0457 \u043f\u0440\u043e\u0444\u0435\u0441\u0456\u0439\u043d\u043e\u0457 \u043a\u0432\u0430\u043b\u0456\u0444\u0456\u043a\u0430\u0446\u0456\u0457 \u0430\u0431\u043e \u044f\u043a\u0443 \u0432\u0456\u043d \u043c\u043e\u0436\u0435 \u0432\u0438\u043a\u043e\u043d\u0443\u0432\u0430\u0442\u0438 \u043f\u0456\u0441\u043b\u044f \u043f\u043e\u043f\u0435\u0440\u0435\u0434\u043d\u044c\u043e\u0433\u043e \u043d\u0430\u0432\u0447\u0430\u043d\u043d\u044f.<\/li>\n<\/ul>\n<p>\u041a\u0440\u0456\u043c \u0446\u044c\u043e\u0433\u043e, \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043d\u0435 \u0431\u0443\u0434\u0435 \u0441\u043f\u043b\u0430\u0447\u0435\u043d\u043e, \u0430 \u0437\u0440\u043e\u0431\u043b\u0435\u043d\u0443 \u0440\u0430\u043d\u0456\u0448\u0435 \u043e\u043f\u043b\u0430\u0442\u0443 \u0431\u0443\u0434\u0435 \u0432\u0456\u0434\u043a\u043b\u0438\u043a\u0430\u043d\u043e, \u044f\u043a\u0449\u043e \u0432 \u043f\u0435\u0440\u0456\u043e\u0434 \u00ab\u0445\u0432\u043e\u0440\u043e\u0431\u0438\u00bb \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a \u0432\u0438\u043a\u043e\u043d\u0443\u0454 \u0456\u043d\u0448\u0443 \u043e\u043f\u043b\u0430\u0447\u0443\u0432\u0430\u043d\u0443 \u0440\u043e\u0431\u043e\u0442\u0443 \u0430\u0431\u043e \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454 \u0446\u0435\u0439 \u0447\u0430\u0441 \u0434\u043b\u044f \u0456\u043d\u0448\u0438\u0445 \u043d\u0435\u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u0438\u0445 \u0446\u0456\u043b\u0435\u0439.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D0%9A%D0%BE%D0%BB%D0%B8-%D0%BF%D0%BE%D1%87%D0%B8%D0%BD%D0%B0%D1%94-%D0%B4%D1%96%D1%8F%D1%82%D0%B8-%D1%81%D1%82%D1%80%D0%B0%D1%85%D0%BE%D0%B2%D0%BA%D0%B0-%D0%B7-%D1%8F%D0%BA%D0%BE%D0%B3%D0%BE-%D0%B4%D0%BD%D1%8F-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D1%8E%D1%82%D1%8C-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9\"><\/span>\u041a\u043e\u043b\u0438 \u043f\u043e\u0447\u0438\u043d\u0430\u0454 \u0434\u0456\u044f\u0442\u0438 \u0441\u0442\u0440\u0430\u0445\u043e\u0432\u043a\u0430: \u0437 \u044f\u043a\u043e\u0433\u043e \u0434\u043d\u044f \u043e\u043f\u043b\u0430\u0447\u0443\u044e\u0442\u044c \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0414\u043b\u044f \u0442\u0430\u043a\u043e\u0433\u043e \u0442\u0438\u043f\u0443 \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f \u0456\u0441\u043d\u0443\u0454 \u0442.\u0437\u0432.\u00a0<em>\u043f\u0435\u0440\u0456\u043e\u0434 \u043e\u0447\u0456\u043a\u0443\u0432\u0430\u043d\u043d\u044f<\/em>\u00a0(okres wyczekiwania). \u0426\u0435 \u0447\u0430\u0441, \u044f\u043a\u0438\u0439 \u043c\u0430\u0454 \u043f\u0440\u043e\u0439\u0442\u0438 \u0437 \u043c\u043e\u043c\u0435\u043d\u0442\u0443 \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f (\u0443 \u043d\u0430\u0448\u043e\u043c\u0443 \u0432\u0438\u043f\u0430\u0434\u043a\u0443 \u2013 \u0437 \u043f\u043e\u0447\u0430\u0442\u043a\u0443 \u0440\u043e\u0431\u043e\u0442\u0438) \u0434\u043e \u043c\u043e\u043c\u0435\u043d\u0442\u0443, \u043a\u043e\u043b\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u0431\u0443\u0434\u0435 \u043e\u043f\u043b\u0430\u0447\u0435\u043d\u043e.<\/p>\n<p>\u0422\u0430\u043a\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d \u0434\u043b\u044f \u0443\u043c\u043e\u0432 \u043e \u043f\u0440\u0430\u0446\u0435\u00a0<strong>\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u044c 30 \u0434\u043d\u0456\u0432<\/strong>, \u0442\u043e\u0431\u0442\u043e \u0445\u0432\u043e\u0440\u0438\u043c \u0434\u043e \u0437\u0430\u043a\u0456\u043d\u0447\u0435\u043d\u043d\u044f 30-\u0434\u0435\u043d\u043d\u043e\u0433\u043e \u043f\u0435\u0440\u0456\u043e\u0434\u0443 L4 \u043d\u0435 \u043e\u043f\u043b\u0430\u0442\u044f\u0442\u044c. \u0414\u043b\u044f \u0434\u043e\u0431\u0440\u043e\u0432\u0456\u043b\u044c\u043d\u043e\u0433\u043e \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f \u0446\u0435\u0439 \u043f\u0435\u0440\u0456\u043e\u0434 \u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u044c 90 \u0434\u043d\u0456\u0432.<\/p>\n<p>\u041f\u0440\u0438 \u0446\u044c\u043e\u043c\u0443 \u0442\u0435\u0440\u043c\u0456\u043d \u043e\u0447\u0456\u043a\u0443\u0432\u0430\u043d\u043d\u044f\u00a0<strong>\u043d\u0435 \u0440\u043e\u0437\u043f\u043e\u0432\u0441\u044e\u0434\u0436\u0443\u0454\u0442\u044c\u0441\u044f<\/strong>\u00a0\u043d\u0430 \u0442\u0430\u043a\u0456 \u0432\u0438\u043f\u0430\u0434\u043a\u0438:<\/p>\n<ul>\n<li>\u042f\u043a\u0449\u043e \u0437\u0430\u0441\u0442\u0440\u0430\u0445\u043e\u0432\u0430\u043d\u043e \u0432\u0438\u043f\u0443\u0441\u043a\u043d\u0438\u043a\u0456\u0432 \u0448\u043a\u0456\u043b \u0430\u0431\u043e \u0432\u0443\u0437\u0456\u0432 \u043f\u0440\u043e\u0442\u044f\u0433\u043e\u043c 90 \u0434\u043d\u0456\u0432 \u043f\u0456\u0441\u043b\u044f \u0437\u0430\u043a\u0456\u043d\u0447\u0435\u043d\u043d\u044f \u043d\u0430\u0432\u0447\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0437\u0430\u043a\u043b\u0430\u0434\u0443.<\/li>\n<li>\u041a\u043e\u043b\u0438 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0438 \u0431\u0443\u043b\u0438 \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u0456 \u0447\u0435\u0440\u0435\u0437 \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c, \u0441\u043f\u0440\u0438\u0447\u0438\u043d\u0435\u043d\u0443\u00a0\u043d\u0435\u0449\u0430\u0441\u043d\u0438\u043c \u0432\u0438\u043f\u0430\u0434\u043a\u043e\u043c \u043f\u043e \u0434\u043e\u0440\u043e\u0437\u0456 \u043d\u0430 \u0440\u043e\u0431\u043e\u0442\u0443 \u0430\u0431\u043e \u0437 \u0440\u043e\u0431\u043e\u0442\u0438.<\/li>\n<li>\u042f\u043a\u0449\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a \u043c\u0430\u0454 10-\u0440\u0456\u0447\u043d\u0438\u0439 (\u0430\u0431\u043e \u0431\u0456\u043b\u044c\u0448\u0438\u0439) \u0441\u0442\u0430\u0436\u00a0\u043e\u0431\u043e\u0432&#8217;\u044f\u0437\u043a\u043e\u0432\u043e\u0433\u043e \u043c\u0435\u0434\u0438\u0447\u043d\u043e\u0433\u043e \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f.<\/li>\n<\/ul>\n<p>\u041d\u0435 \u043f\u043e\u0448\u0438\u0440\u044e\u0454\u0442\u044c\u0441\u044f \u043e\u0431\u043c\u0435\u0436\u0435\u043d\u043d\u044f \u0442\u0430\u043a\u043e\u0436 \u043d\u0430 \u0434\u0435\u043f\u0443\u0442\u0430\u0442\u0456\u0432, \u0441\u0435\u043d\u0430\u0442\u043e\u0440\u0456\u0432, \u043c\u0438\u0442\u043d\u0438\u043a\u0456\u0432, \u043f\u043e\u0434\u0430\u0442\u043a\u0456\u0432\u0446\u0456\u0432, \u0430\u043b\u0435 \u0441\u0435\u0440\u0435\u0434 \u043d\u0438\u0445 \u0456\u043d\u043e\u0437\u0435\u043c\u0446\u0456\u0432 \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u043e \u043d\u0435\u043c\u0430\u0454.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%AF%D0%BA-%D0%B2%D0%B7%D1%8F%D1%82%D0%B8-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\"><\/span>\u042f\u043a \u0432\u0437\u044f\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0412\u0438\u0434\u0430\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043c\u043e\u0436\u0435 \u043b\u0456\u043a\u0430\u0440, \u0443 \u0442\u043e\u043c\u0443 \u0447\u0438\u0441\u043b\u0456\u00a0\u0441\u0456\u043c\u0435\u0439\u043d\u0438\u0439\u00a0\u0447\u0438 \u0444\u0430\u0445\u0456\u0432\u0435\u0446\u044c. \u0423 \u0434\u0435\u044f\u043a\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445 \u043f\u043e\u0432\u043d\u043e\u0432\u0430\u0436\u0435\u043d\u043d\u044f \u043c\u043e\u0436\u0443\u0442\u044c \u0431\u0443\u0442\u0438 \u043f\u0435\u0440\u0435\u0434\u0430\u043d\u0456 \u0444\u0435\u043b\u044c\u0434\u0448\u0435\u0440\u0430\u043c.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D0%9E%D1%82%D1%80%D0%B8%D0%BC%D0%B0%D0%BD%D0%BD%D1%8F-e-ZLA\"><\/span>\u041e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f e-ZLA<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u042f\u043a \u0443\u0436\u0435 \u0437\u0430\u0437\u043d\u0430\u0447\u0430\u043b\u043e\u0441\u044f, \u0443 \u043f\u0435\u0440\u0435\u0432\u0430\u0436\u043d\u0456\u0439 \u0431\u0456\u043b\u044c\u0448\u043e\u0441\u0442\u0456 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 \u043b\u0456\u043a\u0430\u0440 \u043e\u0444\u043e\u0440\u043c\u043b\u044f\u0454 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 (e-ZLA). \u0414\u043b\u044f \u0446\u044c\u043e\u0433\u043e \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0430 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u044f \u0432\u0432\u043e\u0434\u0438\u0442\u044c\u0441\u044f \u0434\u043e PUE ZUS.<\/p>\n<p>\u0412\u0456\u0434\u0431\u0443\u0442\u0438\u0441\u044f \u0446\u0435 \u043c\u043e\u0436\u0435 \u0456 \u043f\u0456\u0434 \u0447\u0430\u0441 \u0432\u0456\u0434\u0432\u0456\u0434\u0443\u0432\u0430\u043d\u043d\u044f \u043b\u0456\u043a\u0430\u0440\u044f \u0432 \u043f\u043e\u043b\u0456\u043a\u043b\u0456\u043d\u0456\u0446\u0456, \u0456 \u043f\u0440\u0438 \u0433\u043e\u0441\u043f\u0456\u0442\u0430\u043b\u0456\u0437\u0430\u0446\u0456\u0457, \u043f\u0440\u0438\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/health\/pogotowie-ratunkowe.html\">\u0435\u043a\u0441\u0442\u0440\u0435\u043d\u0456\u0439 \u0434\u043e\u043f\u043e\u043c\u043e\u0437\u0456<\/a>\u00a0\u0430\u0431\u043e \u043d\u0430\u0434\u0430\u043d\u043d\u044f \u043f\u043e\u0441\u043b\u0443\u0433 \u0432\u0434\u043e\u043c\u0430.<\/p>\n<p><strong>\u041f\u0430\u043f\u0435\u0440\u043e\u0432\u0430 \u0432\u0435\u0440\u0441\u0456\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043d\u0430 \u0434\u0430\u043d\u0438\u0439 \u043c\u043e\u043c\u0435\u043d\u0442 \u043d\u0435 \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0430<\/strong>, \u0430\u043b\u0435 \u0432\u043e\u043d\u0430 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u043d\u0430\u0434\u0430\u043d\u0430 \u043d\u0430 \u0432\u0438\u043c\u043e\u0433\u0443 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430. \u041a\u0440\u0456\u043c \u0446\u044c\u043e\u0433\u043e, \u043e\u0444\u043e\u0440\u043c\u0438\u0442\u0438 \u043f\u0430\u043f\u0435\u0440\u043e\u0432\u0438\u0439 ZUS ZLA (\u043d\u0430 \u0437\u0430\u0437\u0434\u0430\u043b\u0435\u0433\u0456\u0434\u044c \u0440\u043e\u0437\u0434\u0440\u0443\u043a\u043e\u0432\u0430\u043d\u043e\u043c\u0443 \u0431\u043b\u0430\u043d\u043a\u0443 \u0437 \u0443\u043d\u0456\u043a\u0430\u043b\u044c\u043d\u0438\u043c \u043d\u043e\u043c\u0435\u0440\u043e\u043c) \u043b\u0456\u043a\u0430\u0440 \u043c\u043e\u0436\u0435 \u0437\u0430 \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u043e\u0441\u0442\u0456 \u0456\u043d\u0442\u0435\u0440\u043d\u0435\u0442\u0443 \u0430\u0431\u043e \u0456\u043d\u0448\u0438\u0445 \u0442\u0435\u0445\u043d\u0456\u0447\u043d\u0438\u0445 \u043f\u0440\u043e\u0431\u043b\u0435\u043c. \u041e\u0434\u043d\u0430\u043a \u043f\u0456\u0437\u043d\u0456\u0448\u0435 \u0432\u0456\u043d \u0431\u0443\u0434\u0435 \u0437\u043e\u0431\u043e\u0432&#8217;\u044f\u0437\u0430\u043d\u0438\u0439 \u0432\u043d\u0435\u0441\u0442\u0438 \u0434\u0430\u043d\u0456 \u0434\u043e \u0441\u0438\u0441\u0442\u0435\u043c\u0438 (\u0441\u0444\u043e\u0440\u043c\u0443\u0432\u0430\u0442\u0438 e-ZLA).<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D0%9F%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%BB%D0%B5%D0%BD%D0%BD%D1%8F-%D1%80%D0%BE%D0%B1%D0%BE%D1%82%D0%BE%D0%B4%D0%B0%D0%B2%D1%86%D1%8F-%D0%BF%D1%80%D0%BE-%D1%85%D0%B2%D0%BE%D1%80%D0%BE%D0%B1%D1%83\"><\/span>\u041f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u043f\u0440\u043e \u0445\u0432\u043e\u0440\u043e\u0431\u0443<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0422\u0443\u0442 \u0432\u0438\u043d\u0438\u043a\u0430\u044e\u0442\u044c \u0434\u0435\u044f\u043a\u0456 \u0440\u043e\u0437\u0431\u0456\u0436\u043d\u043e\u0441\u0442\u0456 \u2013 \u0447\u0438 \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u043e \u0441\u043f\u043e\u0432\u0456\u0449\u0430\u0442\u0438 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u043f\u0440\u043e \u0445\u0432\u043e\u0440\u043e\u0431\u0443, \u044f\u043a\u0449\u043e \u0432\u0456\u043d \u043c\u043e\u0436\u0435 \u043f\u043e\u0431\u0430\u0447\u0438\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u0441\u0438\u0441\u0442\u0435\u043c\u0456 PUE ZUS, \u0430\u043a\u0430\u0443\u043d\u0442 \u0443 \u044f\u043a\u0456\u0439 \u043f\u043e\u0432\u0438\u043d\u0435\u043d \u043c\u0430\u0442\u0438 \u0449\u0435 \u0437 2023 \u0440\u043e\u043a\u0443?<\/p>\n<p>\u0421\u043f\u0440\u0430\u0432\u0434\u0456, \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u043c\u043e\u0436\u0435 \u043f\u043e\u0431\u0430\u0447\u0438\u0442\u0438 e-ZLA, \u0441\u0444\u043e\u0440\u043c\u043e\u0432\u0430\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u0435\u043c \u0439\u043e\u0433\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0430. \u041e\u0434\u043d\u0430\u043a \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u043d\u0435 \u0437\u043e\u0431\u043e\u0432&#8217;\u044f\u0437\u0430\u043d\u0438\u0439 \u0443 \u0449\u043e\u0434\u0435\u043d\u043d\u043e\u043c\u0443 \u0440\u0435\u0436\u0438\u043c\u0456 \u043c\u043e\u043d\u0456\u0442\u043e\u0440\u0438\u0442\u0438 \u0434\u0430\u043d\u0456 \u0441\u0438\u0441\u0442\u0435\u043c\u0438, \u0449\u043e\u0431 \u0437&#8217;\u044f\u0441\u043e\u0432\u0443\u0432\u0430\u0442\u0438 \u043d\u0430\u044f\u0432\u043d\u0456\u0441\u0442\u044c \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0456\u0432, \u0449\u043e \u0437\u0430\u0445\u0432\u043e\u0440\u0456\u043b\u0438.<\/p>\n<div class=\"colored\">\u0420\u043e\u0431\u0456\u0442\u043d\u0438\u043a \u0437\u043e\u0431\u043e\u0432&#8217;\u044f\u0437\u0430\u043d\u0438\u0439 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u043f\u0440\u043e \u0445\u0432\u043e\u0440\u043e\u0431\u0443 \u043d\u0435\u0433\u0430\u0439\u043d\u043e.<\/div>\n<p>\u0423 \u043d\u0430\u0434\u0437\u0432\u0438\u0447\u0430\u0439\u043d\u0438\u0445 \u0441\u0438\u0442\u0443\u0430\u0446\u0456\u044f\u0445 (\u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u043f\u0440\u0438 \u043d\u0435\u0449\u0430\u0441\u043d\u043e\u043c\u0443 \u0432\u0438\u043f\u0430\u0434\u043a\u0443 \u0447\u0438 \u043e\u0431&#8217;\u0454\u043a\u0442\u0438\u0432\u043d\u0438\u0445 \u0447\u0438\u043d\u043d\u0438\u043a\u0430\u0445, \u0449\u043e \u043f\u0435\u0440\u0435\u0448\u043a\u043e\u0434\u0436\u0430\u044e\u0442\u044c \u0442\u0430\u043a\u043e\u043c\u0443 \u043e\u043f\u043e\u0432\u0456\u0449\u0435\u043d\u043d\u044e) \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a \u043c\u043e\u0436\u0435 \u0441\u043f\u043e\u0432\u0456\u0441\u0442\u0438\u0442\u0438 \u0437\u0433\u043e\u0434\u043e\u043c, \u0430\u043b\u0435 \u043d\u0435 \u043f\u0456\u0437\u043d\u0456\u0448\u0435 \u0434\u0440\u0443\u0433\u043e\u0433\u043e \u0434\u043d\u044f \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u043e\u0441\u0442\u0456 \u0447\u0438 \u0434\u0440\u0443\u0433\u043e\u0433\u043e \u0434\u043d\u044f \u043f\u0456\u0441\u043b\u044f \u043f\u0440\u0438\u043f\u0438\u043d\u0435\u043d\u043d\u044f \u043f\u0435\u0440\u0435\u0448\u043a\u043e\u0434\u0436\u0430\u044e\u0447\u0438\u0445 \u043f\u0440\u0438\u0447\u0438\u043d.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D0%A5%D1%82%D0%BE-%D1%96-%D1%8F%D0%BA-%D0%BC%D0%BE%D0%B6%D0%B5-%D0%BF%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%B8%D1%82%D0%B8\"><\/span>\u0425\u0442\u043e \u0456 \u044f\u043a \u043c\u043e\u0436\u0435 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0420\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u043f\u043e\u0432\u0438\u043d\u0435\u043d \u0437\u0430\u0437\u0434\u0430\u043b\u0435\u0433\u0456\u0434\u044c \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438 \u0440\u043e\u0431\u0456\u0442\u043d\u0438\u043a\u0430\u043c \u0441\u043f\u043e\u0441\u043e\u0431\u0438 \u0441\u043f\u043e\u0432\u0456\u0449\u0435\u043d\u043d\u044f \u043f\u0440\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439. \u0426\u0435 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0437\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u043e \u0431\u0435\u0437\u043f\u043e\u0441\u0435\u0440\u0435\u0434\u043d\u044c\u043e \u0443 \u0442\u0440\u0443\u0434\u043e\u0432\u043e\u043c\u0443 \u043a\u043e\u043d\u0442\u0440\u0430\u043a\u0442\u0456,\u00a0\u043a\u043e\u043b\u0435\u043a\u0442\u0438\u0432\u043d\u043e\u043c\u0443 \u0434\u043e\u0433\u043e\u0432\u043e\u0440\u0456, \u0432 \u043e\u043a\u0440\u0435\u043c\u043e\u043c\u0443 \u0440\u0435\u0433\u043b\u0430\u043c\u0435\u043d\u0442\u0456 \u0447\u0438 \u0456\u043d\u0448\u043e\u043c\u0443 \u0432\u043d\u0443\u0442\u0440\u0456\u0448\u043d\u044c\u043e\u043c\u0443 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u0456.<\/p>\n<p>\u042f\u043a\u0449\u043e \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u043d\u0435 \u0432\u043a\u0430\u0437\u0430\u0432 \u0441\u0432\u043e\u0454\u0447\u0430\u0441\u043d\u043e \u0441\u043f\u043e\u0441\u043e\u0431\u0438 \u043e\u043f\u043e\u0432\u0456\u0449\u0435\u043d\u043d\u044f, \u043c\u043e\u0436\u0443\u0442\u044c \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0432\u0430\u0442\u0438\u0441\u044c \u0431\u0443\u0434\u044c-\u044f\u043a\u0456 \u0437 \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u0438\u0445:<\/p>\n<ul>\n<li>\u043e\u0441\u043e\u0431\u0438\u0441\u0442\u0435 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f;<\/li>\n<li>\u0447\u0435\u0440\u0435\u0437 \u0456\u043d\u0448\u0443 \u043e\u0441\u043e\u0431\u0443;<\/li>\n<li>\u043f\u043e \u0442\u0435\u043b\u0435\u0444\u043e\u043d\u0443;<\/li>\n<li>\u0437\u0430 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u043e\u044e \u0442\u0435\u043a\u0441\u0442\u043e\u0432\u043e\u0433\u043e \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f, email;<\/li>\n<li><a href=\"https:\/\/poland-consult.com\/uk\/posluhy\/poshta\/list-polecony.html\">\u0440\u0435\u043a\u043e\u043c\u0435\u043d\u0434\u043e\u0432\u0430\u043d\u0438\u043c \u043b\u0438\u0441\u0442\u043e\u043c<\/a>.<\/li>\n<\/ul>\n<h4><span class=\"ez-toc-section\" id=\"%D0%9D%D0%B0%D1%81%D0%BB%D1%96%D0%B4%D0%BA%D0%B8-%D0%B2%D1%96%D0%B4%D1%81%D1%83%D1%82%D0%BD%D0%BE%D1%81%D1%82%D1%96-%D0%BF%D0%BE%D0%B2%D1%96%D0%B4%D0%BE%D0%BC%D0%BB%D0%B5%D0%BD%D0%BD%D1%8F\"><\/span>\u041d\u0430\u0441\u043b\u0456\u0434\u043a\u0438 \u0432\u0456\u0434\u0441\u0443\u0442\u043d\u043e\u0441\u0442\u0456 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u042f\u043a\u0449\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a \u043d\u0435 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u044c \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u043e \u0434\u043e \u0432\u0438\u0449\u0435\u0437\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0445 \u043f\u0440\u0430\u0432\u0438\u043b, \u0446\u0435 \u0431\u0443\u0434\u0435 \u0432\u0432\u0430\u0436\u0430\u0442\u0438\u0441\u044f \u0434\u0438\u0441\u0446\u0438\u043f\u043b\u0456\u043d\u0430\u0440\u043d\u0438\u043c \u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f\u043c, \u044f\u043a\u0435 \u043c\u043e\u0436\u0435 \u043f\u0440\u0438\u0437\u0432\u0435\u0441\u0442\u0438 \u0434\u043e \u043f\u043e\u043f\u0435\u0440\u0435\u0434\u0436\u0435\u043d\u043d\u044f \u0447\u0438\u00a0\u0434\u043e\u0433\u0430\u043d\u0438, \u0430 \u0432 \u043e\u0441\u043e\u0431\u043b\u0438\u0432\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445 \u0456 \u0434\u043e\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/robota\/zvilnennya\/zwolnienie-dyscyplinarne.html\">\u0440\u043e\u0437\u0456\u0440\u0432\u0430\u043d\u043d\u044f \u0434\u043e\u0433\u043e\u0432\u043e\u0440\u0443 \u0431\u0435\u0437 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u043b\u0435\u043d\u043d\u044f<\/a>.<\/p>\n<p>\u0423 \u043a\u043e\u0436\u043d\u043e\u043c\u0443 \u0432\u0438\u043f\u0430\u0434\u043a\u0443 \u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f, \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u043e, \u043e\u043f\u043b\u0430\u0442\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043d\u0435 \u043f\u0440\u043e\u0432\u043e\u0434\u0438\u0442\u044c\u0441\u044f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9A%D0%BE%D0%BB%D0%B8-%D0%BF%D0%BE%D1%87%D0%B8%D0%BD%D0%B0%D1%94-%D0%B4%D1%96%D1%8F%D1%82%D0%B8-ZUS-ZLA\"><\/span>\u041a\u043e\u043b\u0438 \u043f\u043e\u0447\u0438\u043d\u0430\u0454 \u0434\u0456\u044f\u0442\u0438 ZUS ZLA?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u041b\u0456\u043a\u0430\u0440 \u043c\u043e\u0436\u0435 \u0432\u0438\u0434\u0430\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0437 \u0434\u043d\u044f \u0437\u0432\u0435\u0440\u043d\u0435\u043d\u043d\u044f. \u0423 \u0432\u0438\u043d\u044f\u0442\u043a\u043e\u0432\u0438\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445 L4 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u043d\u0430\u0434\u0430\u043d\u0438\u0439 \u0437\u0430\u0434\u043d\u0456\u043c \u0447\u0438\u0441\u043b\u043e\u043c, \u043f\u0440\u043e\u0442\u0435 \u043d\u0435 \u0440\u0430\u043d\u0456\u0448\u0435 \u043d\u0456\u0436 \u0437\u0430 3 \u0434\u043d\u0456 \u0434\u043e \u0434\u0430\u0442\u0438 \u0437\u0432\u0435\u0440\u043d\u0435\u043d\u043d\u044f.<\/p>\n<p>\u0414\u0430\u043d\u0435 \u043e\u0431\u043c\u0435\u0436\u0435\u043d\u043d\u044f \u043d\u0435 \u0434\u0456\u0454, \u043a\u043e\u043b\u0438 \u0439\u0434\u0435\u0442\u044c\u0441\u044f\u00a0\u043f\u0440\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439, \u0432\u0438\u0434\u0430\u043d\u0438\u0439 \u043f\u0441\u0438\u0445\u0456\u0430\u0442\u0440\u043e\u043c, \u044f\u043a\u0449\u043e \u043b\u0456\u043a\u0430\u0440 \u043c\u0430\u0454 \u043f\u0456\u0434\u0441\u0442\u0430\u0432\u0438 \u043f\u0440\u0438\u043f\u0443\u0441\u043a\u0430\u0442\u0438, \u0449\u043e \u0443 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430 \u043e\u0431\u043c\u0435\u0436\u0435\u043d\u043d\u044f \u0437\u0434\u0430\u0442\u043d\u043e\u0441\u0442\u0456 \u043e\u0446\u0456\u043d\u044e\u0432\u0430\u0442\u0438 \u0440\u0435\u0430\u043b\u044c\u043d\u0456\u0441\u0442\u044c.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%AF%D0%BA-%D0%BF%D0%B5%D1%80%D0%B5%D0%B2%D1%96%D1%80%D0%B8%D1%82%D0%B8-%D1%81%D0%B2%D1%96%D0%B9-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96\"><\/span>\u042f\u043a \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u0438\u0442\u0438 \u0441\u0432\u0456\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0423 \u041f\u043e\u043b\u044c\u0449\u0456 \u043c\u043e\u0436\u043b\u0438\u0432\u0456\u0441\u0442\u044c \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0443 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u0456\u0432 L4 \u043f\u0435\u0440\u0435\u0434\u0431\u0430\u0447\u0430\u0454\u0442\u044c\u0441\u044f \u0447\u0435\u0440\u0435\u0437 \u041f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0443 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0438\u0445 \u043f\u043e\u0441\u043b\u0443\u0433 \u0417\u0423\u0421 (<a href=\"https:\/\/poland-consult.com\/uk\/europa\/polska\/dovidnik\/pue-zus.html\">PUE ZUS<\/a>). \u0414\u043e\u0441\u0442\u0430\u0442\u043d\u044c\u043e \u0430\u0432\u0442\u043e\u0440\u0438\u0437\u0443\u0432\u0430\u0442\u0438\u0441\u044c \u0443 \u0441\u0435\u0440\u0432\u0456\u0441\u0456 \u0442\u0430 \u0432 \u043e\u0441\u043e\u0431\u0438\u0441\u0442\u043e\u043c\u0443 \u043a\u0430\u0431\u0456\u043d\u0435\u0442\u0456 \u0431\u0443\u0434\u0435 \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u0430 \u0432\u0441\u044f \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u0430 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u044f.<\/p>\n<p>\u0414\u043e\u0441\u0442\u0430\u0442\u043d\u044c\u043e \u0432\u0438\u043a\u043e\u043d\u0430\u0442\u0438 \u0432\u0441\u044c\u043e\u0433\u043e \u0434\u0432\u0430 \u043a\u0440\u043e\u043a\u0438:<\/p>\n<ol>\n<li>\u041f\u0435\u0440\u0435\u0439\u0434\u0456\u0442\u044c \u043d\u0430 <a href=\"https:\/\/www.zus.pl\/ezus\/logowanie\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\u0441\u0442\u043e\u0440\u0456\u043d\u043a\u0443 \u0441\u0435\u0440\u0432\u0456\u0441\u0443<\/a> \u0442\u0430 \u0430\u0432\u0442\u043e\u0440\u0438\u0437\u0443\u0439\u0442\u0435\u0441\u044c.<\/li>\n<li>\u0412\u0438\u0431\u0435\u0440\u0456\u0442\u044c \u0432\u043a\u043b\u0430\u0434\u043a\u0443 <code>Za\u015bwiadczenia lekarskie<\/code>.<\/li>\n<\/ol>\n<p><img decoding=\"async\" src=\"https:\/\/poland-consult.com\/wp-content\/uploads\/2024\/02\/l4-101.jpg\" alt=\"\u042f\u043a \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u0438\u0442\u0438 \u0441\u0432\u0456\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456\" width=\"750\" height=\"559\" class=\"alignnone size-full wp-image-103878\" \/><\/p>\n<p>\u0422\u0443\u0442 \u043c\u043e\u0436\u043d\u0430 \u0437\u043d\u0430\u0439\u0442\u0438 \u0432\u0441\u0456 \u0444\u043e\u0440\u043c\u0438 \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u043e\u0433\u043e ZLA, \u0432\u0438\u043f\u0443\u0449\u0435\u043d\u0438\u0445 \u043e\u0441\u0442\u0430\u043d\u043d\u0456\u043c \u0447\u0430\u0441\u043e\u043c.<\/p>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\">\u041f\u043b\u0430\u0442\u0444\u043e\u0440\u043c\u0430 \u043d\u0430\u0434\u0430\u0454 \u043c\u043e\u0436\u043b\u0438\u0432\u0456\u0441\u0442\u044c \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0430\u0442\u0438 \u043f\u043e\u0432\u043d\u0443 \u0444\u043e\u0440\u043c\u0443 eZLA. \u0414\u043b\u044f \u0446\u044c\u043e\u0433\u043e \u0432\u0438\u0431\u0435\u0440\u0456\u0442\u044c L4, \u0449\u043e \u0432\u0430\u0441 \u0446\u0456\u043a\u0430\u0432\u0438\u0442\u044c, \u0430 \u043f\u043e\u0442\u0456\u043c \u043d\u0430\u0442\u0438\u0441\u043d\u0456\u0442\u044c \u043d\u0430 \u043e\u043f\u0446\u0456\u044e \u043f\u043e\u043f\u0435\u0440\u0435\u0434\u043d\u044c\u043e\u0433\u043e \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434\u0443.<\/div><\/div>\n<p>\u0406\u043d\u0448\u0438\u043c \u0441\u043f\u043e\u0441\u043e\u0431\u043e\u043c \u0454 \u0406\u043d\u0442\u0435\u0440\u043d\u0435\u0442-\u043a\u0430\u0431\u0456\u043d\u0435\u0442 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430. \u0429\u043e\u0431 \u043d\u0438\u043c \u0441\u043a\u043e\u0440\u0438\u0441\u0442\u0430\u0442\u0438\u0441\u044f, \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e \u043c\u0430\u0442\u0438 \u043e\u0431\u043b\u0456\u043a\u043e\u0432\u0438\u0439 \u0437\u0430\u043f\u0438\u0441 \u0456 \u0430\u0432\u0442\u043e\u0440\u0438\u0437\u0443\u0432\u0430\u0442\u0438\u0441\u044f \u0432 IKP, \u0430 \u0434\u0430\u043b\u0456 \u0437\u043d\u0430\u0439\u0442\u0438 \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u0443 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u044e \u0432 \u0440\u043e\u0437\u0434\u0456\u043b\u0456\u00a0<code>\"Historia leczenia\"<\/code>\u00a0\u0443 \u0432\u043a\u043b\u0430\u0434\u0446\u0456\u00a0<code>\"Zwolnienia\"<\/code>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%AF%D0%BA-%D0%BE%D0%BF%D0%BB%D0%B0%D1%87%D1%83%D1%94%D1%82%D1%8C%D1%81%D1%8F-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%B8%D0%B9-%D1%83-%D0%9F%D0%BE%D0%BB%D1%8C%D1%89%D1%96-%D0%BF%D0%BE-UoP\"><\/span>\u042f\u043a \u043e\u043f\u043b\u0430\u0447\u0443\u0454\u0442\u044c\u0441\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043f\u043e UoP?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u041d\u0430\u0441\u0430\u043c\u043f\u0435\u0440\u0435\u0434 \u0437\u0433\u0430\u0434\u0430\u0454\u043c\u043e, \u0449\u043e:<\/p>\n<ul>\n<li>\u0434\u043b\u044f \u043e\u0441\u0456\u0431 \u0434\u043e 50 \u0440\u043e\u043a\u0456\u0432 \u043f\u0435\u0440\u0448\u0456 33 \u0434\u043d\u0456 \u043e\u043f\u043b\u0430\u0447\u0443\u0454 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c, \u0430 \u0434\u0430\u043b\u0456 ZUS;<\/li>\n<li>\u0434\u043b\u044f \u043e\u0441\u0456\u0431 50+ \u0440\u043e\u043a\u0456\u0432 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u0432\u0438\u043f\u043b\u0430\u0447\u0443\u0454 \u043b\u0438\u0448\u0435 14 \u0434\u043d\u0456\u0432, \u0434\u0430\u043b\u0456 \u043f\u0435\u0440\u0435\u0434\u0430\u044e\u0447\u0438 \u043f\u043e\u0432\u043d\u043e\u0432\u0430\u0436\u0435\u043d\u043d\u044f ZUS.<\/li>\n<\/ul>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\">\u0420\u043e\u0437\u0433\u043b\u044f\u0434\u0430\u0454\u0442\u044c\u0441\u044f \u0437\u0430\u043a\u043e\u043d\u043e\u043f\u0440\u043e\u0435\u043a\u0442, \u0449\u043e \u043f\u0435\u0440\u0435\u0434\u0430\u0454 \u043e\u043f\u043b\u0430\u0442\u0443 \u0434\u043e ZUS \u0437 \u043f\u0435\u0440\u0448\u043e\u0433\u043e \u0434\u043d\u044f. \u041a\u043e\u043b\u0438 \u0442\u0430 \u044f\u043a\u0449\u043e \u043f\u043e\u043f\u0440\u0430\u0432\u043a\u0438 \u0431\u0443\u0434\u0443\u0442\u044c \u043f\u0440\u0438\u0439\u043d\u044f\u0442\u0456, \u0446\u0435\u0439 \u043c\u0430\u0442\u0435\u0440\u0456\u0430\u043b \u0431\u0443\u0434\u0435 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u043e.<\/div><\/div>\n<p>\u0417 \u0442\u043e\u0447\u043a\u0438 \u0437\u043e\u0440\u0443 \u0440\u0456\u0432\u043d\u044f \u043e\u043f\u043b\u0430\u0442\u0438, \u0434\u043b\u044f \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0430 \u0446\u0435 \u043d\u0435 \u043c\u0430\u0454 \u0432\u0435\u043b\u0438\u043a\u043e\u0433\u043e \u0437\u043d\u0430\u0447\u0435\u043d\u043d\u044f, \u043e\u0441\u043a\u0456\u043b\u044c\u043a\u0438 \u0432\u0441\u0456 182 \u0434\u043d\u0456, \u043d\u0430 \u044f\u043a\u0456 \u043c\u043e\u0436\u043b\u0438\u0432\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439, \u043e\u043f\u043b\u0430\u0447\u0443\u0454\u0442\u044c\u0441\u044f \u043e\u0434\u043d\u0430\u043a\u043e\u0432\u043e. \u041e\u0434\u043d\u0430\u043a \u0446\u0435 \u043c\u043e\u0436\u0435 \u0432\u043f\u043b\u0438\u0432\u0430\u0442\u0438 \u043d\u0430 \u0434\u0430\u0442\u0438 \u0432\u0438\u043f\u043b\u0430\u0442 \u2013 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c \u0437\u0430\u0437\u0432\u0438\u0447\u0430\u0439 \u043f\u043b\u0430\u0442\u0438\u0442\u044c \u0443 \u0437\u0432\u0438\u0447\u043d\u0456 \u0434\u043d\u0456 \u0437\u0430\u0440\u043f\u043b\u0430\u0442\u0438, \u0430 ZUS \u043c\u043e\u0436\u0435 \u0432\u0441\u0442\u0430\u043d\u043e\u0432\u043b\u044e\u0432\u0430\u0442\u0438 \u0441\u0432\u043e\u0457 \u0442\u0435\u0440\u043c\u0456\u043d\u0438.<\/p>\n<p>\u0429\u043e \u0441\u0442\u043e\u0441\u0443\u0454\u0442\u044c\u0441\u044f \u0440\u0456\u0432\u043d\u0456\u0432 \u043e\u043f\u043b\u0430\u0442\u0438 \u0437\u0430 L4, \u0442\u043e \u0432\u043e\u043d\u0438 \u0442\u0430\u043a\u0456:<\/p>\n<ul>\n<li>\u0423 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/health\/wypadek.html\">\u043d\u0435\u0449\u0430\u0441\u043d\u043e\u0433\u043e \u0432\u0438\u043f\u0430\u0434\u043a\u0443 \u043d\u0430 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0446\u0442\u0432\u0456<\/a>, \u0445\u0432\u043e\u0440\u043e\u0431\u0438 \u043f\u0456\u0434 \u0447\u0430\u0441 \u0432\u0430\u0433\u0456\u0442\u043d\u043e\u0441\u0442\u0456 \u0447\u0438 \u043f\u0440\u043e\u0445\u043e\u0434\u0436\u0435\u043d\u043d\u044f \u0430\u043d\u0430\u043b\u0456\u0437\u0456\u0432 \u043a\u0430\u043d\u0434\u0438\u0434\u0430\u0442\u0456\u0432 \u0443 \u0434\u043e\u043d\u043e\u0440\u0438 \u043a\u043b\u0456\u0442\u0438\u043d, \u0442\u043a\u0430\u043d\u0438\u043d \u0442\u0430 \u043e\u0440\u0433\u0430\u043d\u0456\u0432 \u0447\u0438 \u043f\u0440\u043e\u0446\u0435\u0434\u0443\u0440\u0438 \u0457\u0445 \u0437\u0431\u043e\u0440\u0443 \u2014 \u043e\u043f\u043b\u0430\u0442\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u044c 100%\u00a0<em>\u0432\u0456\u0434 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u043e\u0432\u043e\u0457 \u0431\u0430\u0437\u0438<\/em>.<\/li>\n<li>\u0423 \u0440\u0435\u0448\u0442\u0456 \u0432\u0438\u043f\u0430\u0434\u043a\u0456\u0432 \u2013 80%\u00a0<em>\u0432\u0456\u0434 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u043e\u0432\u043e\u0457 \u0431\u0430\u0437\u0438<\/em>.<\/li>\n<\/ul>\n<p>\u041e\u0447\u0435\u0432\u0438\u0434\u043d\u043e, \u0449\u043e \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e \u0432\u0438\u0437\u043d\u0430\u0447\u0438\u0442\u0438, \u044f\u043a \u0432\u0441\u0442\u0430\u043d\u043e\u0432\u043b\u044e\u0454\u0442\u044c\u0441\u044f \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u043e\u0432\u0430 \u0431\u0430\u0437\u0430.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D0%AF%D0%BA-%D0%B2%D0%B8%D0%B7%D0%BD%D0%B0%D1%87%D0%B0%D1%94%D1%82%D1%8C%D1%81%D1%8F-%D1%80%D0%BE%D0%B7%D1%80%D0%B0%D1%85%D1%83%D0%BD%D0%BA%D0%BE%D0%B2%D0%B0-%D0%B1%D0%B0%D0%B7%D0%B0-%D0%BD%D0%B0-%D0%BE%D0%BF%D0%BB%D0%B0%D1%82%D1%83-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%BE%D0%B3%D0%BE\"><\/span>\u042f\u043a \u0432\u0438\u0437\u043d\u0430\u0447\u0430\u0454\u0442\u044c\u0441\u044f \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u043e\u0432\u0430 \u0431\u0430\u0437\u0430 \u043d\u0430 \u043e\u043f\u043b\u0430\u0442\u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u041f\u0456\u0434\u0441\u0442\u0430\u0432\u043e\u044e \u0434\u043b\u044f \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u0432\u0438\u043d\u0430\u0433\u043e\u0440\u043e\u0434\u0438 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0443 \u0454\u00a0<strong>\u0441\u0435\u0440\u0435\u0434\u043d\u044c\u043e\u043c\u0456\u0441\u044f\u0447\u043d\u0430 \u043e\u043f\u043b\u0430\u0442\u0430 \u043f\u0440\u0430\u0446\u0456<\/strong>, \u0434\u043b\u044f \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u044f\u043a\u043e\u0457:<\/p>\n<ul>\n<li>\u0412\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u0432\u0435\u043b\u0438\u0447\u0438\u043d\u0430 \u0437\u0430 12 \u043a\u0430\u043b\u0435\u043d\u0434\u0430\u0440\u043d\u0438\u0445 \u043c\u0456\u0441\u044f\u0446\u0456\u0432, \u0449\u043e \u043f\u0435\u0440\u0435\u0434\u0443\u044e\u0442\u044c \u0442\u043e\u043c\u0443, \u0432 \u044f\u043a\u043e\u043c\u0443 \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439,\u00a0<em>\u0430\u0431\u043e<\/em><\/li>\n<li>\u0417\u0430\u0441\u0442\u043e\u0441\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u0441\u0435\u0440\u0435\u0434\u043d\u044f \u0437\u0430 \u043f\u043e\u0432\u043d\u0456 \u043a\u0430\u043b\u0435\u043d\u0434\u0430\u0440\u043d\u0456 \u043c\u0456\u0441\u044f\u0446\u0456 \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f, \u044f\u043a\u0449\u043e \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c \u043d\u0430\u0441\u0442\u0430\u043b\u0430 \u0434\u043e \u0437\u0430\u043a\u0456\u043d\u0447\u0435\u043d\u043d\u044f \u043a\u0430\u043b\u0435\u043d\u0434\u0430\u0440\u043d\u043e\u0433\u043e \u0440\u043e\u043a\u0443 \u0441\u0442\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f.<\/li>\n<\/ul>\n<p>\u041a\u0440\u0456\u043c \u0441\u043a\u043b\u0430\u0434\u043e\u0432\u0438\u0445 \u043e\u043f\u043b\u0430\u0442\u0438 \u043f\u0440\u0430\u0446\u0456, \u0449\u043e \u043d\u0430\u043b\u0435\u0436\u0438\u0442\u044c \u0437\u0430 \u043c\u0456\u0441\u044f\u0447\u043d\u0456 \u043f\u0435\u0440\u0456\u043e\u0434\u0438, \u043e\u0441\u043d\u043e\u0432\u043e\u044e \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u0440\u0435\u0437\u0435\u0440\u0432\u0443 \u0432\u043a\u043b\u044e\u0447\u0430\u044e\u0442\u044c\u0441\u044f \u0447\u0430\u0441\u0442\u0438\u043d\u0438 \u0432\u0438\u043d\u0430\u0433\u043e\u0440\u043e\u0434\u0438 \u0437\u0430 \u043f\u0435\u0440\u0456\u043e\u0434\u0438 \u0442\u0440\u0438\u0432\u0430\u043b\u0456\u0441\u0442\u044e \u043f\u043e\u043d\u0430\u0434 \u043c\u0456\u0441\u044f\u0446\u044c. \u041d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434:<\/p>\n<ol>\n<li>\u041a\u0432\u0430\u0440\u0442\u0430\u043b\u044c\u043d\u0456 \u043f\u0440\u0435\u043c\u0456\u0457 \u0432\u043a\u043b\u044e\u0447\u0430\u044e\u0442\u044c\u0441\u044f \u0434\u043e \u0431\u0430\u0437\u0438 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u0443 \u0440\u043e\u0437\u043c\u0456\u0440\u0456 1\/12 \u0441\u0443\u043c, \u0432\u0438\u043f\u043b\u0430\u0447\u0435\u043d\u0438\u0445 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u043e\u0432\u0456 \u0437\u0430 4 \u043a\u0430\u043b\u0435\u043d\u0434\u0430\u0440\u043d\u0456 \u043a\u0432\u0430\u0440\u0442\u0430\u043b\u0438, \u0449\u043e \u043f\u0435\u0440\u0435\u0434\u0443\u044e\u0442\u044c \u043c\u0456\u0441\u044f\u0446\u044e, \u0443 \u044f\u043a\u043e\u043c\u0443 \u0432\u0438\u043d\u0438\u043a\u043b\u0430 \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c.<\/li>\n<li>\u041f\u0440\u0435\u043c\u0456\u0457 \u0437\u0430 \u0440\u0456\u0447\u043d\u0456 \u043f\u0435\u0440\u0456\u043e\u0434\u0438 \u0432\u043a\u043b\u044e\u0447\u0430\u044e\u0442\u044c\u0441\u044f \u0432 \u043e\u0441\u043d\u043e\u0432\u0443 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0447\u0435\u0440\u0435\u0437 \u0445\u0432\u043e\u0440\u043e\u0431\u0443 \u0443 \u0440\u043e\u0437\u043c\u0456\u0440\u0456 1\/12 \u0441\u0443\u043c\u0438, \u0432\u0438\u043f\u043b\u0430\u0447\u0435\u043d\u043e\u0457 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u043e\u0432\u0456 \u0437\u0430 \u043a\u0430\u043b\u0435\u043d\u0434\u0430\u0440\u043d\u0438\u0439 \u0440\u0456\u043a, \u0449\u043e \u043f\u0435\u0440\u0435\u0434\u0443\u0454 \u043c\u0456\u0441\u044f\u0446\u044e, \u0443 \u044f\u043a\u043e\u043c\u0443 \u0432\u0438\u043d\u0438\u043a\u043b\u0430 \u043d\u0435\u043f\u0440\u0430\u0446\u0435\u0437\u0434\u0430\u0442\u043d\u0456\u0441\u0442\u044c.<\/li>\n<\/ol>\n<p>\u042f\u043a\u0449\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0443 \u0431\u0443\u043b\u043e \u043d\u0430\u0434\u0430\u043d\u043e \u0447\u0430\u0441\u0442\u0438\u043d\u0443 \u0432\u0438\u043d\u0430\u0433\u043e\u0440\u043e\u0434\u0438 \u043b\u0438\u0448\u0435 \u0434\u043e \u043f\u0435\u0432\u043d\u043e\u0457 \u0434\u0430\u0442\u0438 (\u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u043d\u0430\u0434\u0431\u0430\u0432\u043a\u0430 \u0437\u0430 \u0432\u0438\u0441\u043b\u0443\u0433\u0443 \u0440\u043e\u043a\u0456\u0432), \u0442\u043e \u043f\u0440\u0438 \u0432\u0438\u0437\u043d\u0430\u0447\u0435\u043d\u043d\u0456 \u043e\u0441\u043d\u043e\u0432\u0438 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u0447\u0435\u0440\u0435\u0437 \u0445\u0432\u043e\u0440\u043e\u0431\u0443 \u0446\u044f \u0447\u0430\u0441\u0442\u0438\u043d\u0430 \u0432\u0440\u0430\u0445\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u043b\u0438\u0448\u0435 \u0437\u0430 \u043f\u0435\u0440\u0456\u043e\u0434 \u0434\u043e \u0446\u0456\u0454\u0457 \u0434\u0430\u0442\u0438.<\/p>\n<div id=\"expertPlagin_ng-82093\" class=\"cs-expertPlagin-tpl\" style=\"background: #Array;background: -moz-linear-gradient(left, #Array 0%, #Array 100%);background: -webkit-linear-gradient(left, #Array 0%,#Array 100%);background: linear-gradient(to right, #Array 0%,#Array 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#Array, endColorstr=#Array,GradientType=1 );\"><div class=\"head_expertPlagin-top\"><span class=\"thumb_expertPlagin-item\" style=\"background-image:url(https:\/\/poland-consult.com\/wp-content\/uploads\/2016\/11\/circle.png)\"><\/span><div class=\"expect-left\"><div class=\"marker_expertPlagin-item\" style=\"background: #db193c;background: -moz-linear-gradient(left, #db193c 0%, #d80027 100%);background: -webkit-linear-gradient(left, #db193c 0%,#d80027 100%);background: linear-gradient(to right, #db193c 0%,#d80027 100%);filter: progid:DXImageTransform.Microsoft.gradient( startColorstr=#db193c, endColorstr=#d80027,GradientType=1 );\">\u041a\u043e\u043d\u0441\u0443\u043b\u044c\u0442\u0430\u043d\u0442<\/div><div class=\"name_expertPlagin-item\">\u0414\u043c\u0438\u0442\u0440\u043e \u041a\u043e\u0441\u0442\u044f\u043d\u0442\u0438\u043d\u043e\u0432\u0438\u0447<\/div><div class=\"descexpert_expertPlagin-item\"><a href=\"https:\/\/t.me\/polandconsult\" target=\"_blank\" rel=\"nofollow noopener\">\u041f\u0456\u0434\u043f\u0438\u0448\u0438\u0441\u044c \u043d\u0430 \u043d\u0430\u0448 Telegram-\u043a\u0430\u043d\u0430\u043b<\/a>, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0432 \u043a\u0443\u0440\u0441\u0456 \u0432\u0430\u0436\u043b\u0438\u0432\u0438\u0445 \u043d\u043e\u0432\u0438\u043d \u0442\u0430 \u043e\u043d\u043e\u0432\u043b\u0435\u043d\u044c.<\/div><\/div><\/div><div class=\"descpage_expertPlagin-item\">\u041f\u0440\u0438 \u0446\u044c\u043e\u043c\u0443 \u0434\u043b\u044f \u0440\u043e\u0431\u0456\u0442\u043d\u0438\u043a\u0456\u0432, \u044f\u043a\u0456 \u043f\u0440\u0430\u0446\u044e\u044e\u0442\u044c \u043f\u043e\u0432\u043d\u0438\u0439 \u0440\u043e\u0431\u043e\u0447\u0438\u0439 \u0434\u0435\u043d\u044c, \u0431\u0430\u0437\u0430 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0443 \u043d\u0435 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u043d\u0438\u0436\u0447\u043e\u044e\u00a0<a href=\"https:\/\/poland-consult.com\/uk\/robota\/zarplata\/minimalna-zarplata.html\">\u043c\u0456\u043d\u0456\u043c\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0440\u043e\u0437\u043c\u0456\u0440\u0443 \u043e\u043f\u043b\u0430\u0442\u0438 \u043f\u0440\u0430\u0446\u0456<\/a>\u00a0\u0437\u0430 \u0432\u0438\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f\u043c \u0441\u0443\u043c\u0438, \u0449\u043e \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u0430\u0454 13,71% \u0446\u0456\u0454\u0457 \u0437\u0430\u0440\u043e\u0431\u0456\u0442\u043d\u043e\u0457 \u043f\u043b\u0430\u0442\u0438.<\/div><\/div>\n<p>\u0423 \u043c\u0435\u0440\u0435\u0436\u0456 \u043c\u043e\u0436\u043d\u0430 \u0437\u0443\u0441\u0442\u0440\u0456\u0442\u0438 \u0431\u0430\u0433\u0430\u0442\u043e \u043a\u0430\u043b\u044c\u043a\u0443\u043b\u044f\u0442\u043e\u0440\u0456\u0432, \u044f\u043a\u0456 \u0434\u043e\u043f\u043e\u043c\u0430\u0433\u0430\u044e\u0442\u044c \u0437 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0430\u043c\u0438 \u0440\u043e\u0437\u043c\u0456\u0440\u0456\u0432 \u0432\u0438\u043f\u043b\u0430\u0442 \u043f\u043e \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443, \u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434,\u00a0<a href=\"https:\/\/kalkulatory.gofin.pl\/kalkulatory\/kalkulator-wynagrodzenia-chorobowego\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\u043d\u0430 \u0441\u0430\u0439\u0442\u0456 gofin.pl<\/a>, \u0430\u043b\u0435 \u0442\u043e\u0447\u043d\u0456 \u0434\u0430\u043d\u0456 \u0437\u043c\u043e\u0436\u0435 \u043f\u043e\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438 \u043b\u0438\u0448\u0435 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440\u0456\u044f, \u043f\u0440\u043e\u0432\u0456\u0432\u0448\u0438 \u0432\u0441\u0456 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0438 \u0437 \u0443\u0440\u0430\u0445\u0443\u0432\u0430\u043d\u043d\u044f\u043c \u0440\u0456\u0437\u043d\u0438\u0445 \u043d\u044e\u0430\u043d\u0441\u0456\u0432.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A7%D0%B8-%D0%BC%D0%BE%D0%B6%D0%BD%D0%B0-%D0%B4%D0%BE%D0%BC%D0%BE%D0%B2%D0%B8%D1%82%D0%B8%D1%81%D1%8F-%D0%B7-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%B5%D0%BC-%D1%8F%D0%BA%D1%89%D0%BE-%D0%BD%D0%B5-%D1%85%D0%B2%D0%BE%D1%80%D1%96%D1%94%D1%88\"><\/span>\u0427\u0438 \u043c\u043e\u0436\u043d\u0430 \u0434\u043e\u043c\u043e\u0432\u0438\u0442\u0438\u0441\u044f \u0437 \u043b\u0456\u043a\u0430\u0440\u0435\u043c, \u044f\u043a\u0449\u043e \u043d\u0435 \u0445\u0432\u043e\u0440\u0456\u0454\u0448?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u042f\u043a\u0449\u043e \u0439\u0434\u0435\u0442\u044c\u0441\u044f \u043f\u0440\u043e \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043d\u0435\u0437\u0430\u043a\u043e\u043d\u043d\u0438\u043c \u0448\u043b\u044f\u0445\u043e\u043c, \u0442\u043e \u0446\u044c\u043e\u0433\u043e \u0440\u043e\u0431\u0438\u0442\u0438 \u043d\u0435 \u0432\u0430\u0440\u0442\u043e. \u0406 ZUS, \u0456 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0435\u0446\u044c\u00a0\u043c\u043e\u0436\u0443\u0442\u044c \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u044f\u0442\u0438 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430\u00a0\u043d\u0430 \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u0443 \u043f\u043e\u0432\u0435\u0434\u0456\u043d\u043a\u0443.<\/p>\n<p>\u042f\u043a\u0449\u043e \u0431\u0443\u0434\u0435 \u0434\u043e\u0432\u0435\u0434\u0435\u043d\u043e \u043d\u0435\u0437\u0430\u043a\u043e\u043d\u043d\u0435 \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e, \u0430, \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u043e, \u0439 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u043f\u043e \u043d\u044c\u043e\u043c\u0443, \u043c\u043e\u0436\u0443\u0442\u044c \u0431\u0443\u0442\u0438 \u043f\u0440\u0435\u0434&#8217;\u044f\u0432\u043b\u0435\u043d\u0456 \u0437\u0432\u0438\u043d\u0443\u0432\u0430\u0447\u0435\u043d\u043d\u044f \u043e\u0434\u0440\u0430\u0437\u0443 \u0437\u0430 \u043a\u0456\u043b\u044c\u043a\u043e\u043c\u0430 \u0441\u0442\u0430\u0442\u0442\u044f\u043c\u0438 \u043a\u0440\u0438\u043c\u0456\u043d\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u0437\u0430\u043a\u043e\u043d\u043e\u0434\u0430\u0432\u0441\u0442\u0432\u0430.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A7%D0%B8-%D0%BC%D0%BE%D0%B6%D0%B5-ZUS-%D0%B2%D1%96%D0%B4%D0%BA%D0%BB%D0%B8%D0%BA%D0%B0%D1%82%D0%B8-%D1%81%D0%BF%D0%BB%D0%B0%D1%82%D1%83-%D0%BB%D1%96%D0%BA%D0%B0%D1%80%D0%BD%D1%8F%D0%BD%D0%BE%D0%B3%D0%BE-%D0%B7%D0%B0-%D0%BF%D0%BE%D1%80%D1%83%D1%88%D0%B5%D0%BD%D0%BD%D1%8F\"><\/span>\u0427\u0438 \u043c\u043e\u0436\u0435 ZUS \u0432\u0456\u0434\u043a\u043b\u0438\u043a\u0430\u0442\u0438 \u0441\u043f\u043b\u0430\u0442\u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u0437\u0430 \u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0415\u043a\u0441\u043f\u0435\u0440\u0442\u0438 ZUS \u043c\u0430\u044e\u0442\u044c \u043f\u0440\u0430\u0432\u043e \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u044f\u0442\u0438 \u0456 \u0432\u0456\u0440\u043d\u0456\u0441\u0442\u044c \u043f\u043e\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u043e\u0433\u043e \u0434\u0456\u0430\u0433\u043d\u043e\u0437\u0443 (\u0447\u0438 \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u0437\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u043e\u043c\u0443 \u0432\u0438\u043f\u0430\u0434\u043a\u0443), \u0456 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0456\u0441\u0442\u044c \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u0430\u043d\u043d\u044f \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u043e\u043c \u0447\u0430\u0441\u0443 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 (\u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u0447\u0438 \u043d\u0435 \u043f\u0440\u0430\u0446\u044e\u0454 \u0432 \u0456\u043d\u0448\u043e\u043c\u0443 \u043c\u0456\u0441\u0446\u0456, \u0447\u0438 \u043d\u0435 \u0433\u0443\u043b\u044f\u0454 \u043d\u0430 \u0432\u0435\u0447\u0456\u0440\u043a\u0430\u0445 \u0437\u0430\u043c\u0456\u0441\u0442\u044c \u043b\u0456\u043a\u0443\u0432\u0430\u043d\u043d\u044f).<\/p>\n<p>\u042f\u043a\u0449\u043e \u0444\u0430\u0445\u0456\u0432\u0446\u0456 \u0437\u043c\u043e\u0436\u0443\u0442\u044c \u0434\u043e\u0432\u0435\u0441\u0442\u0438 \u043f\u043e\u0440\u0443\u0448\u0435\u043d\u043d\u044f, \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0431\u0443\u0434\u0435 \u0430\u043d\u0443\u043b\u044c\u043e\u0432\u0430\u043d\u0438\u0439, \u0430 \u0440\u0430\u043d\u0456\u0448\u0435 \u0432\u0438\u043f\u043b\u0430\u0447\u0435\u043d\u0456 \u043a\u043e\u0448\u0442\u0438 \u0434\u043e\u0432\u0435\u0434\u0435\u0442\u044c\u0441\u044f \u043f\u043e\u0432\u0435\u0440\u043d\u0443\u0442\u0438. \u041d\u0430\u0441\u043a\u0456\u043b\u044c\u043a\u0438 \u0442\u0430\u043a\u0456 \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u043a\u0438 \u0447\u0430\u0441\u0442\u0456 \u0442\u0430 \u0441\u0443\u0432\u043e\u0440\u0456 \u043c\u043e\u0436\u043d\u0430 \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u0442\u0438 \u0437 \u043e\u0444\u0456\u0446\u0456\u0439\u043d\u043e\u0457 \u0441\u0442\u0430\u0442\u0438\u0441\u0442\u0438\u043a\u0438 \u2013 \u043b\u0438\u0448\u0435 \u0437\u0430 2023 \u0440\u0456\u043a \u0434\u043e \u0431\u044e\u0434\u0436\u0435\u0442\u0443 \u0431\u0443\u043b\u043e \u043f\u043e\u0432\u0435\u0440\u043d\u0443\u0442\u043e \u043c\u0430\u0439\u0436\u0435\u00a0<strong>148 \u043c\u043b\u043d \u0437\u043b\u043e\u0442\u0438\u0445<\/strong>.<\/p>\n<div class=\"zakon\">\n<h2><span class=\"ez-toc-section\" id=\"%D0%9F%D0%BE%D1%88%D0%B8%D1%80%D0%B5%D0%BD%D1%96-%D0%B7%D0%B0%D0%BF%D0%B8%D1%82%D0%B0%D0%BD%D0%BD%D1%8F\"><\/span>\u041f\u043e\u0448\u0438\u0440\u0435\u043d\u0456 \u0437\u0430\u043f\u0438\u0442\u0430\u043d\u043d\u044f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"expert-review-faq expert-review-faq--style-style-2 expert-review-faq--color-blue-2\"><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u042f\u043a \u043d\u0430\u0437\u0438\u0432\u0430\u0454\u0442\u044c\u0441\u044f \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u041e\u0444\u0456\u0446\u0456\u0439\u043d\u043e \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u044e\u0442\u044c\u0441\u044f \u0430\u0431\u0440\u0435\u0432\u0456\u0430\u0442\u0443\u0440\u0438 ZUS ZLA \u0442\u0430 e-ZLA, \u043e\u0434\u043d\u0430\u043a \u0443 \u0440\u043e\u0437\u043c\u043e\u0432\u043d\u0456\u0439 \u043c\u043e\u0432\u0456 \u0447\u0430\u0441\u0442\u043e \u0437\u0430\u0441\u0442\u043e\u0441\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u0441\u0442\u0430\u0440\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d Zwolnienie L4 \u0430\u0431\u043e \u043f\u0440\u043e\u0441\u0442\u043e L4.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u0427\u0438 \u043c\u043e\u0436\u043d\u0430 \u043e\u0444\u043e\u0440\u043c\u0438\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043e\u043d\u043b\u0430\u0439\u043d?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u041b\u0456\u043a\u0430\u0440\u0456, \u044f\u043a\u0456 \u0432\u0456\u0434\u043a\u0440\u0438\u0432\u0430\u044e\u0442\u044c \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0456 \u043b\u0438\u0441\u0442\u0438, \u0440\u043e\u0431\u043b\u044f\u0442\u044c \u0446\u0435 \u0437\u0434\u0435\u0431\u0456\u043b\u044c\u0448\u043e\u0433\u043e \u043e\u043d\u043b\u0430\u0439\u043d \u0447\u0435\u0440\u0435\u0437 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u044c\u043d\u0435 \u043f\u0440\u043e\u0433\u0440\u0430\u043c\u043d\u0435 \u0437\u0430\u0431\u0435\u0437\u043f\u0435\u0447\u0435\u043d\u043d\u044f. \u041e\u0434\u043d\u0430\u043a \u0432\u0438\u0434\u0430\u0442\u0438 L4 \u0431\u0435\u0437 \u043e\u0441\u043e\u0431\u0438\u0441\u0442\u043e\u0433\u043e \u043e\u0433\u043b\u044f\u0434\u0443 \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430 \u043c\u043e\u0436\u043d\u0430 \u043b\u0438\u0448\u0435 \u0443 \u0432\u0438\u043d\u044f\u0442\u043a\u043e\u0432\u0438\u0445, \u043e\u043a\u0440\u0435\u043c\u043e \u043f\u0440\u043e\u043f\u0438\u0441\u0430\u043d\u0438\u0445 \u0443 \u0437\u0430\u043a\u043e\u043d\u0430\u0445 \u0432\u0438\u043f\u0430\u0434\u043a\u0430\u0445.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u0427\u0438 \u043c\u043e\u0436\u0443\u0442\u044c \u0437\u0432\u0456\u043b\u044c\u043d\u0438\u0442\u0438 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u0432 \u041f\u043e\u043b\u044c\u0449\u0456?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u0417\u0432\u0456\u043b\u044c\u043d\u0438\u0442\u0438 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u043c\u043e\u0436\u043d\u0430 \u043b\u0438\u0448\u0435 \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a\u0430, \u044f\u043a\u0438\u0439 \u043f\u0440\u043e\u043f\u0440\u0430\u0446\u044e\u0432\u0430\u0432 \u043c\u0435\u043d\u0448\u0435 \u043f\u0456\u0432\u0440\u043e\u043a\u0443 \u0456 \u043f\u0435\u0440\u0435\u0431\u0443\u0432\u0430\u0454 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u043f\u043e\u043d\u0430\u0434 3 \u043c\u0456\u0441\u044f\u0446\u0456. \u041f\u0440\u0438 \u0431\u0456\u043b\u044c\u0448\u043e\u043c\u0443 \u0441\u0442\u0430\u0436\u0456 \u0437\u0432\u0456\u043b\u044c\u043d\u0435\u043d\u043d\u044f \u0434\u043e\u043f\u0443\u0441\u0442\u0438\u043c\u0435 \u0432\u0438\u043a\u043b\u044e\u0447\u043d\u043e \u043f\u0440\u0438 \u0445\u0432\u043e\u0440\u043e\u0431\u0456 \u0432\u0435\u0441\u044c \u0434\u043e\u043f\u0443\u0441\u0442\u0438\u043c\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e (182 \u0430\u0431\u043e 270 \u0434\u043d\u0456\u0432) \u0442\u0430 \u043f\u0435\u0440\u0435\u0431\u0443\u0432\u0430\u043d\u043d\u044f \u0449\u0435 3-\u0445 \u043c\u0456\u0441\u044f\u0446\u0456\u0432 \u043d\u0430 \u0440\u0435\u0430\u0431\u0456\u043b\u0456\u0442\u0430\u0446\u0456\u0439\u043d\u0456\u0439 \u0434\u043e\u043f\u043e\u043c\u043e\u0437\u0456.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u042f\u043a\u0456 \u0454 \u043a\u043e\u0434\u0438 \u0445\u0432\u043e\u0440\u043e\u0431 \u0443 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u043b\u0438\u0441\u0442\u043a\u0443?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u0423 L4 \u0432\u0456\u0434\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0456 \u0442\u0430\u043a\u0456 \u043a\u043e\u0434\u0438: A \u2013 \u043f\u043e\u0432\u0442\u043e\u0440\u043d\u0435 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f \u0437 \u0442\u0438\u043c \u0441\u0430\u043c\u0438\u043c \u0434\u0456\u0430\u0433\u043d\u043e\u0437\u043e\u043c, B \u2013 \u0432\u0430\u0433\u0456\u0442\u043d\u0456\u0441\u0442\u044c, C \u2013 \u0437\u043b\u043e\u0432\u0436\u0438\u0432\u0430\u043d\u043d\u044f \u0430\u043b\u043a\u043e\u0433\u043e\u043b\u0435\u043c, D \u2013 \u0442\u0443\u0431\u0435\u0440\u043a\u0443\u043b\u044c\u043e\u0437, E \u2013 \u0456\u043d\u0444\u0435\u043a\u0446\u0456\u0439\u043d\u0435 \u0437\u0430\u0445\u0432\u043e\u0440\u044e\u0432\u0430\u043d\u043d\u044f \u0437 \u0456\u043d\u043a\u0443\u0431\u0430\u0446\u0456\u0439\u043d\u0438\u043c \u043f\u0435\u0440\u0456\u043e\u0434\u043e\u043c \u043f\u043e\u043d\u0430\u0434 14 \u0434\u043d\u0456\u0432.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u042f\u043a \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043f\u043b\u0430\u0442\u044f\u0442\u044c \u0437\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u0420\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043e\u043a \u0432\u0456\u0434\u0431\u0443\u0432\u0430\u0454\u0442\u044c\u0441\u044f \u043d\u0430 \u043f\u0456\u0434\u0441\u0442\u0430\u0432\u0456 \u0441\u0435\u0440\u0435\u0434\u043d\u044c\u043e\u0457 \u0437\u0430\u0440\u043f\u043b\u0430\u0442\u0438 \u0437\u0430 12 \u043c\u0456\u0441\u044f\u0446\u0456\u0432 (\u0430\u0431\u043e \u0437\u0430 \u043c\u0435\u043d\u0448\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d, \u044f\u043a\u0449\u043e \u043f\u0440\u0430\u0446\u0456\u0432\u043d\u0438\u043a \u0449\u0435 \u043d\u0435 \u0432\u0456\u0434\u043f\u0440\u0430\u0446\u044e\u0432\u0430\u0432 \u0440\u0456\u043a). \u041e\u0434\u043d\u0430\u043a \u0454 \u0432 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043a\u0430\u0445 \u0456 \u0456\u043d\u0448\u0456 \u0441\u043a\u043b\u0430\u0434\u043d\u043e\u0441\u0442\u0456, \u0442\u043e\u043c\u0443 \u0442\u043e\u0447\u043d\u0438\u0439 \u0440\u043e\u0437\u0440\u0430\u0445\u0443\u043d\u043e\u043a \u043c\u043e\u0436\u0435 \u0437\u0440\u043e\u0431\u0438\u0442\u0438 \u043b\u0438\u0448\u0435 \u0431\u0443\u0445\u0433\u0430\u043b\u0442\u0435\u0440\u0456\u044f.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u0427\u0438 \u043c\u043e\u0436\u043d\u0430 \u0432\u0438\u0457\u0436\u0434\u0436\u0430\u0442\u0438 \u0437\u0430 \u043a\u043e\u0440\u0434\u043e\u043d \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u0432 \u041f\u043e\u043b\u044c\u0449\u0456?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u0412\u0438\u0457\u0437\u0434 \u043c\u043e\u0436\u043b\u0438\u0432\u0438\u0439 \u043b\u0438\u0448\u0435 \u0437\u0430 \u043f\u043e\u043a\u0430\u0437\u0430\u043d\u043d\u044f\u043c\u0438 \u043b\u0456\u043a\u0430\u0440\u044f (\u043d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u0434\u043b\u044f \u043f\u0440\u043e\u0445\u043e\u0434\u0436\u0435\u043d\u043d\u044f \u043b\u0456\u043a\u0443\u0432\u0430\u043d\u043d\u044f). \u0421\u0430\u043c\u043e\u0432\u0456\u043b\u044c\u043d\u0438\u0439 \u0432\u0438\u0457\u0437\u0434 \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0440\u043e\u0437\u0446\u0456\u043d\u0435\u043d\u0438\u0439 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u0435\u043c \u0430\u0431\u043e ZUS \u044f\u043a \u043d\u0435\u0446\u0456\u043b\u044c\u043e\u0432\u0435 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u0430\u043d\u043d\u044f L4 \u0456, \u044f\u043a \u043d\u0430\u0441\u043b\u0456\u0434\u043e\u043a, \u0430\u043d\u0443\u043b\u044e\u0432\u0430\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u0421\u043a\u0456\u043b\u044c\u043a\u0438 \u043c\u043e\u0436\u043d\u0430 \u0431\u0443\u0442\u0438 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u0432 \u041f\u043e\u043b\u044c\u0449\u0456?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u041c\u0430\u043a\u0441\u0438\u043c\u0430\u043b\u044c\u043d\u0438\u0439 \u0442\u0435\u0440\u043c\u0456\u043d \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u0433\u043e \u043b\u0438\u0441\u0442\u0430 \u2013 182 \u0434\u043d\u0456 (\u043f\u0440\u0438 \u0432\u0430\u0433\u0456\u0442\u043d\u043e\u0441\u0442\u0456 \u0447\u0438 \u0442\u0443\u0431\u0435\u0440\u043a\u0443\u043b\u044c\u043e\u0437\u0456 \u0442\u0435\u0440\u043c\u0456\u043d \u0434\u043e 270 \u0434\u043d\u0456\u0432). \u041d\u0430 \u0431\u0456\u043b\u044c\u0448\u0438\u0439 \u043f\u0435\u0440\u0456\u043e\u0434 \u043e\u0444\u043e\u0440\u043c\u043b\u044f\u0454\u0442\u044c\u0441\u044f \u043e\u043a\u0440\u0435\u043c\u0438\u0439 \u0432\u0438\u0434 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u2013 \u0440\u0435\u0430\u0431\u0456\u043b\u0456\u0442\u0430\u0446\u0456\u0439\u043d\u0430 \u043f\u0456\u043b\u044c\u0433\u0430 \u0447\u0438 \u043f\u0435\u043d\u0441\u0456\u044f \u043f\u043e \u0456\u043d\u0432\u0430\u043b\u0456\u0434\u043d\u043e\u0441\u0442\u0456.<\/div><\/div><div class=\"expert-review-faq-item\">  <div class=\"expert-review-faq-item__question js-expert-review-faq-item-question\">\u0414\u0435 \u043f\u043e\u0434\u0438\u0432\u0438\u0442\u0438\u0441\u044c \u0435\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0438\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456?<\/div>  <div class=\"expert-review-faq-item__answer js-expert-review-faq-item-answer\" style=\"display:none\">\u041f\u043e\u0431\u0430\u0447\u0438\u0442\u0438 \u0441\u0432\u0456\u0439 L4 \u043a\u043e\u0436\u0435\u043d \u0437\u0430\u0441\u0442\u0440\u0430\u0445\u043e\u0432\u0430\u043d\u0438\u0439 \u043c\u043e\u0436\u0435 \u0432 \u043e\u0441\u043e\u0431\u0438\u0441\u0442\u043e\u043c\u0443 \u043a\u0430\u0431\u0456\u043d\u0435\u0442\u0456 \u0456\u043d\u0442\u0435\u0440\u043d\u0435\u0442-\u043f\u0440\u043e\u0444\u0456\u043b\u044e \u043f\u0430\u0446\u0456\u0454\u043d\u0442\u0430 (IKP) \u0430\u0431\u043e \u0447\u0435\u0440\u0435\u0437 \u043f\u0440\u043e\u0444\u0456\u043b\u044c PUE ZUS.<\/div><\/div><\/div><\/div>\n<p><strong>\u041f\u0456\u0434\u0441\u0443\u043c\u0443\u0454\u043c\u043e<\/strong>. \u041b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442 \u043f\u0440\u0438 \u0440\u043e\u0431\u043e\u0442\u0456 \u043f\u043e \u0443\u043c\u043e\u0432\u0456 \u043e \u043f\u0440\u0430\u0446\u0435 \u0432 \u041f\u043e\u043b\u044c\u0449\u0456 \u043e\u043f\u043b\u0430\u0447\u0443\u0454\u0442\u044c\u0441\u044f \u0437\u0430 \u0437\u0430\u043c\u043e\u0432\u0447\u0443\u0432\u0430\u043d\u043d\u044f\u043c. \u041e\u0434\u043d\u0430\u043a \u0434\u043b\u044f \u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u043a\u043e\u0448\u0442\u0456\u0432 \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e \u0432\u0447\u0430\u0441\u043d\u043e \u0441\u043f\u043e\u0432\u0456\u0441\u0442\u0438\u0442\u0438 \u0440\u043e\u0431\u043e\u0442\u043e\u0434\u0430\u0432\u0446\u044f, \u0430 \u0447\u0430\u0441 \u043d\u0430 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u043e\u043c\u0443 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u0430\u0442\u0438 \u0437\u0430 \u043f\u0440\u0438\u0437\u043d\u0430\u0447\u0435\u043d\u043d\u044f\u043c, \u0456\u043d\u0430\u043a\u0448\u0435 \u043a\u043e\u0448\u0442\u0438 \u0434\u043e\u0432\u0435\u0434\u0435\u0442\u044c\u0441\u044f \u043f\u043e\u0432\u0435\u0440\u043d\u0443\u0442\u0438, \u0430 \u043d\u0430 \u0440\u043e\u0431\u043e\u0442\u0456 \u043f\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0442\u044c \u043f\u0440\u043e\u0433\u0443\u043b\u0438.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;96444&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;3&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;3\\\/5 - (2 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;\u042f\u043a \u0432\u0437\u044f\u0442\u0438 \u0442\u0430 \u043f\u0435\u0440\u0435\u0432\u0456\u0440\u0438\u0442\u0438 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u0443 \u041f\u043e\u043b\u044c\u0449\u0456 \u043f\u043e \u0423\u043c\u043e\u0432\u0456 \u043e \u043f\u0440\u0430\u0446\u0435?&quot;,&quot;width&quot;:&quot;82&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 82px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            3\/5 - (2 votes)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"\u042f\u043a\u0449\u043e \u043e\u0431\u0441\u0442\u0430\u0432\u0438\u043d\u0438 \u0441\u043a\u043b\u0430\u043b\u0438\u0441\u044f \u0442\u0430\u043a, \u0449\u043e \u043b\u044e\u0434\u0438\u043d\u0430 \u0437\u0430\u0445\u0432\u043e\u0440\u0456\u043b\u0430 \u0456 \u043d\u0435 \u043c\u043e\u0436\u0435 \u044f\u043a\u0438\u0439\u0441\u044c \u0447\u0430\u0441 \u043f\u0440\u0430\u0446\u044e\u0432\u0430\u0442\u0438, \u043b\u0456\u043a\u0430\u0440 \u0432\u0438\u043f\u0438\u0441\u0443\u0454 \u0457\u0439 \u043b\u0456\u043a\u0430\u0440\u043d\u044f\u043d\u0438\u0439 \u043b\u0438\u0441\u0442.&hellip;","protected":false},"author":1,"featured_media":79848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","footnotes":""},"categories":[700,625],"tags":[],"class_list":{"0":"post-96444","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-likarnyanij","8":"category-umowy-o-prace","9":"cs-entry"},"_links":{"self":[{"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/posts\/96444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/comments?post=96444"}],"version-history":[{"count":0,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/posts\/96444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/media\/79848"}],"wp:attachment":[{"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/media?parent=96444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/categories?post=96444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poland-consult.com\/uk\/wp-json\/wp\/v2\/tags?post=96444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}